{"id":118812,"date":"2023-07-10T23:08:40","date_gmt":"2023-07-11T02:08:40","guid":{"rendered":"https:\/\/noticiasmercedinas.com\/site\/?p=118812"},"modified":"2023-07-10T23:08:40","modified_gmt":"2023-07-11T02:08:40","slug":"se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos","status":"publish","type":"post","link":"https:\/\/noticiasmercedinas.com\/site\/2023\/07\/10\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\/","title":{"rendered":"Se inaugur\u00f3 el pavimento en Barrio Esperanza, una obra que transforma la vida de los vecinos"},"content":{"rendered":"<div dir=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-118814\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2023\/07\/DSC07632-1024x682.jpg\" alt=\"\" width=\"640\" height=\"426\" srcset=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2023\/07\/DSC07632-1024x682.jpg 1024w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2023\/07\/DSC07632-300x200.jpg 300w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2023\/07\/DSC07632-768x512.jpg 768w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2023\/07\/DSC07632-640x427.jpg 640w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2023\/07\/DSC07632-1280x853.jpg 1280w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2023\/07\/DSC07632-681x454.jpg 681w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2023\/07\/DSC07632.jpg 1319w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/div>\n<p>Con una mezcla de emoci\u00f3n y gratitud, el Municipio de Mercedes celebr\u00f3 la inauguraci\u00f3n de 8 nuevas cuadras de pavimento, obras h\u00eddricas y jerarquizaci\u00f3n en el barrio Esperanza. Este hito marca el comienzo de una transformaci\u00f3n integral para la comunidad, con el anuncio de la segunda etapa de asfaltado que completar\u00e1 la totalidad del barrio.<\/p>\n<p>El intendente Juan Ignacio Ustarroz expres\u00f3 su honor y orgullo por el logro alcanzado, felicitando a los trabajadores municipales por su dedicaci\u00f3n y compromiso. \u00abEsto se llama amor, compromiso y trabajo\u00bb, afirm\u00f3 el mandatario local.<\/p>\n<p>En un anuncio que llen\u00f3 de esperanza a los presentes, el intendente Ustarroz comparti\u00f3 que se ha obtenido la habilitaci\u00f3n por parte del Gobierno Provincial para llevar a cabo la segunda etapa de asfaltado en el barrio Esperanza. Adem\u00e1s, mencion\u00f3 otras obras destacadas en la ciudad, como la construcci\u00f3n de la Ruta 15, la Ruta 42 y el impresionante Complejo Cultural La Trocha.<\/p>\n<p>Mirando hacia el futuro, el Dr. Ustarroz enfatiz\u00f3 la importancia de continuar avanzando en el desarrollo de Mercedes, destacando la necesidad de brindar a los ni\u00f1os y j\u00f3venes las mejores condiciones de vida. \u00abNo es solo pisar este asfalto, lo m\u00e1s importante son los chicos, la ni\u00f1ez. Debemos convertir a Mercedes en una ciudad con los mejores clubes, barrios y servicios de salud\u00bb, subray\u00f3.<\/p>\n<p>El secretario de Obras, Emanuel P\u00e9rez Carrera, agradeci\u00f3 a los trabajadores municipales y a las cooperativas involucradas en la obra por su contribuci\u00f3n, destacando que este proyecto beneficia no solo al barrio Esperanza, sino a toda la comunidad de Mercedes. \u00abEstamos abordando obras grandes y peque\u00f1as para el beneficio de nuestra comunidad\u00bb, a\u00f1adi\u00f3.<\/p>\n<p>Desde la Cooperativa La Esperanza, Mauricio Perafan, un vecino del barrio, expres\u00f3 su alegr\u00eda y gratitud por la concreci\u00f3n de un sue\u00f1o largamente anhelado. \u00abHace 34 a\u00f1os que esper\u00e1bamos esta obra de asfalto, y gracias al intendente Ustarroz, este sue\u00f1o se hizo posible\u00bb, comparti\u00f3. Adem\u00e1s, Perafan destac\u00f3 la rapidez y calidad de la obra, realizada con mano de obra cooperativista, y expres\u00f3 su esperanza de que lleguen m\u00e1s proyectos en el futuro.<\/p>\n<p>Carlos Romero, coordinador de las cuadrillas de trabajo municipal, resalt\u00f3 el esfuerzo y la capacitaci\u00f3n de los trabajadores que hicieron posible la obra. \u00abEsto es un gran orgullo para todos nosotros\u00bb, afirm\u00f3 Romero, evidenciando el compromiso y la dedicaci\u00f3n de quienes participaron en el proyecto.<\/p>\n<p>La inauguraci\u00f3n del pavimento en el Barrio Esperanza marca un antes y un despu\u00e9s en la vida de los vecinos, quienes ven mejorar sus condiciones de acceso y calidad de vida. El Municipio de Mercedes contin\u00faa trabajando con el objetivo de transformar la ciudad y brindar oportunidades de crecimiento y bienestar para todos sus habitantes.<\/p>\n<div dir=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-118815\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2023\/07\/DSC07601-1024x682.jpg\" alt=\"\" width=\"640\" height=\"426\" srcset=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2023\/07\/DSC07601-1024x682.jpg 1024w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2023\/07\/DSC07601-300x200.jpg 300w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2023\/07\/DSC07601-768x512.jpg 768w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2023\/07\/DSC07601-640x427.jpg 640w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2023\/07\/DSC07601-1280x853.jpg 1280w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2023\/07\/DSC07601-681x454.jpg 681w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2023\/07\/DSC07601.jpg 1319w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u25a0 Desde la comuna se celebr\u00f3 la inauguraci\u00f3n de 8 nuevas cuadras de pavimento, obras h\u00eddricas y jerarquizaci\u00f3n en el barrio. Y se anunci\u00f3 una segunda etapa de obras<\/p>\n","protected":false},"author":16,"featured_media":118814,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[211,2662],"class_list":["post-118812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad","tag-asfalto","tag-barrio-esperanza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se inaugur\u00f3 el pavimento en Barrio Esperanza, una obra que transforma la vida de los vecinos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasmercedinas.com\/site\/2023\/07\/10\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se inaugur\u00f3 el pavimento en Barrio Esperanza, una obra que transforma la vida de los vecinos\" \/>\n<meta property=\"og:description\" content=\"\u25a0 Desde la comuna se celebr\u00f3 la inauguraci\u00f3n de 8 nuevas cuadras de pavimento, obras h\u00eddricas y jerarquizaci\u00f3n en el barrio. Y se anunci\u00f3 una segunda etapa de obras\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasmercedinas.com\/site\/2023\/07\/10\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\/\" \/>\n<meta property=\"og:site_name\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticiasmercedinas\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-11T02:08:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2023\/07\/DSC07632.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1319\" \/>\n\t<meta property=\"og:image:height\" content=\"879\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:site\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2023\\\/07\\\/10\\\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2023\\\/07\\\/10\\\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\\\/\"},\"author\":{\"name\":\"NOTICIASMERCEDINAS.COM\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/84b59c099c28ff2e8b77d4ceec5d8063\"},\"headline\":\"Se inaugur\u00f3 el pavimento en Barrio Esperanza, una obra que transforma la vida de los vecinos\",\"datePublished\":\"2023-07-11T02:08:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2023\\\/07\\\/10\\\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\\\/\"},\"wordCount\":484,\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2023\\\/07\\\/10\\\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/DSC07632.jpg\",\"keywords\":[\"asfalto\",\"barrio esperanza\"],\"articleSection\":[\"Sociedad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2023\\\/07\\\/10\\\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2023\\\/07\\\/10\\\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\\\/\",\"name\":\"Se inaugur\u00f3 el pavimento en Barrio Esperanza, una obra que transforma la vida de los vecinos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2023\\\/07\\\/10\\\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2023\\\/07\\\/10\\\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/DSC07632.jpg\",\"datePublished\":\"2023-07-11T02:08:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2023\\\/07\\\/10\\\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2023\\\/07\\\/10\\\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2023\\\/07\\\/10\\\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/DSC07632.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/DSC07632.jpg\",\"width\":1319,\"height\":879},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2023\\\/07\\\/10\\\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se inaugur\u00f3 el pavimento en Barrio Esperanza, una obra que transforma la vida de los vecinos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"description\":\"Mercedes, Buenos Aires, Argentina\",\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"width\":512,\"height\":512,\"caption\":\"NOTICIASMERCEDINAS.COM\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticiasmercedinas\\\/\",\"https:\\\/\\\/x.com\\\/notmercedinas\",\"https:\\\/\\\/www.instagram.com\\\/noticiasmercedinas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/84b59c099c28ff2e8b77d4ceec5d8063\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g\",\"caption\":\"NOTICIASMERCEDINAS.COM\"},\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/author\\\/anonimo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se inaugur\u00f3 el pavimento en Barrio Esperanza, una obra que transforma la vida de los vecinos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasmercedinas.com\/site\/2023\/07\/10\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\/","og_locale":"es_ES","og_type":"article","og_title":"Se inaugur\u00f3 el pavimento en Barrio Esperanza, una obra que transforma la vida de los vecinos","og_description":"\u25a0 Desde la comuna se celebr\u00f3 la inauguraci\u00f3n de 8 nuevas cuadras de pavimento, obras h\u00eddricas y jerarquizaci\u00f3n en el barrio. Y se anunci\u00f3 una segunda etapa de obras","og_url":"https:\/\/noticiasmercedinas.com\/site\/2023\/07\/10\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\/","og_site_name":"NOTICIASMERCEDINAS.COM","article_publisher":"https:\/\/www.facebook.com\/noticiasmercedinas\/","article_published_time":"2023-07-11T02:08:40+00:00","og_image":[{"width":1319,"height":879,"url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2023\/07\/DSC07632.jpg","type":"image\/jpeg"}],"author":"NOTICIASMERCEDINAS.COM","twitter_card":"summary_large_image","twitter_creator":"@notmercedinas","twitter_site":"@notmercedinas","twitter_misc":{"Escrito por":"NOTICIASMERCEDINAS.COM","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasmercedinas.com\/site\/2023\/07\/10\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\/#article","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2023\/07\/10\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\/"},"author":{"name":"NOTICIASMERCEDINAS.COM","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/84b59c099c28ff2e8b77d4ceec5d8063"},"headline":"Se inaugur\u00f3 el pavimento en Barrio Esperanza, una obra que transforma la vida de los vecinos","datePublished":"2023-07-11T02:08:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2023\/07\/10\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\/"},"wordCount":484,"publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2023\/07\/10\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2023\/07\/DSC07632.jpg","keywords":["asfalto","barrio esperanza"],"articleSection":["Sociedad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasmercedinas.com\/site\/2023\/07\/10\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\/","url":"https:\/\/noticiasmercedinas.com\/site\/2023\/07\/10\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\/","name":"Se inaugur\u00f3 el pavimento en Barrio Esperanza, una obra que transforma la vida de los vecinos","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2023\/07\/10\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\/#primaryimage"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2023\/07\/10\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2023\/07\/DSC07632.jpg","datePublished":"2023-07-11T02:08:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2023\/07\/10\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasmercedinas.com\/site\/2023\/07\/10\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/2023\/07\/10\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\/#primaryimage","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2023\/07\/DSC07632.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2023\/07\/DSC07632.jpg","width":1319,"height":879},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasmercedinas.com\/site\/2023\/07\/10\/se-inauguro-el-pavimento-en-barrio-esperanza-una-obra-que-transforma-la-vida-de-los-vecinos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noticiasmercedinas.com\/site\/"},{"@type":"ListItem","position":2,"name":"Se inaugur\u00f3 el pavimento en Barrio Esperanza, una obra que transforma la vida de los vecinos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasmercedinas.com\/site\/#website","url":"https:\/\/noticiasmercedinas.com\/site\/","name":"NOTICIASMERCEDINAS.COM","description":"Mercedes, Buenos Aires, Argentina","publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasmercedinas.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasmercedinas.com\/site\/#organization","name":"NOTICIASMERCEDINAS.COM","url":"https:\/\/noticiasmercedinas.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","width":512,"height":512,"caption":"NOTICIASMERCEDINAS.COM"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticiasmercedinas\/","https:\/\/x.com\/notmercedinas","https:\/\/www.instagram.com\/noticiasmercedinas\/"]},{"@type":"Person","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/84b59c099c28ff2e8b77d4ceec5d8063","name":"NOTICIASMERCEDINAS.COM","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g","caption":"NOTICIASMERCEDINAS.COM"},"url":"https:\/\/noticiasmercedinas.com\/site\/author\/anonimo\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/118812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/comments?post=118812"}],"version-history":[{"count":1,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/118812\/revisions"}],"predecessor-version":[{"id":118816,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/118812\/revisions\/118816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media\/118814"}],"wp:attachment":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media?parent=118812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/categories?post=118812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/tags?post=118812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}