{"id":150141,"date":"2024-12-10T09:52:35","date_gmt":"2024-12-10T12:52:35","guid":{"rendered":"https:\/\/noticiasmercedinas.com\/site\/?p=150141"},"modified":"2024-12-10T15:46:37","modified_gmt":"2024-12-10T18:46:37","slug":"el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola","status":"publish","type":"post","link":"https:\/\/noticiasmercedinas.com\/site\/2024\/12\/10\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\/","title":{"rendered":"El ballet se lucir\u00e1 con una noche de danza cl\u00e1sica y espa\u00f1ola"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-150144\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/125f7f3b-c947-4c3f-abac-e319032cbbe5.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/125f7f3b-c947-4c3f-abac-e319032cbbe5.jpg 1280w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/125f7f3b-c947-4c3f-abac-e319032cbbe5-300x169.jpg 300w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/125f7f3b-c947-4c3f-abac-e319032cbbe5-1024x576.jpg 1024w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/125f7f3b-c947-4c3f-abac-e319032cbbe5-768x432.jpg 768w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/125f7f3b-c947-4c3f-abac-e319032cbbe5-640x360.jpg 640w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/125f7f3b-c947-4c3f-abac-e319032cbbe5-681x383.jpg 681w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>El pr\u00f3ximo s\u00e1bado 21 de diciembre a las 21:00 horas, el Teatro Argentino de Mercedes ser\u00e1 escenario de una imperdible Noche de Ballet, presentada por el Estudio de Danza Matilde Zetti de Asenzo bajo la direcci\u00f3n de la profesora Hayde\u00e9 Groba.<\/p>\n<p>El repertorio incluir\u00e1 peque\u00f1as piezas de reconocidos ballets como El Cascanueces, La Gioconda y El Corsario, as\u00ed como un cuadro final dedicado a las danzas t\u00edpicas espa\u00f1olas, en un despliegue de elegancia y t\u00e9cnica que promete cautivar al p\u00fablico.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-150142\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/f4e1a8a3-1e27-417f-a173-18a56ccb9a19.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/f4e1a8a3-1e27-417f-a173-18a56ccb9a19.jpg 1280w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/f4e1a8a3-1e27-417f-a173-18a56ccb9a19-300x169.jpg 300w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/f4e1a8a3-1e27-417f-a173-18a56ccb9a19-1024x576.jpg 1024w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/f4e1a8a3-1e27-417f-a173-18a56ccb9a19-768x432.jpg 768w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/f4e1a8a3-1e27-417f-a173-18a56ccb9a19-640x360.jpg 640w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/f4e1a8a3-1e27-417f-a173-18a56ccb9a19-681x383.jpg 681w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>Adem\u00e1s, esta edici\u00f3n contar\u00e1 con la participaci\u00f3n especial de Mar\u00eda Amelia Colimodio y Javier Marzello, quienes interpretar\u00e1n algunas de las piezas m\u00e1s ic\u00f3nicas del tango, aportando un toque distintivo al festival de este a\u00f1o.<\/p>\n<p>Las entradas ya est\u00e1n a la venta en la boleter\u00eda del teatro, en los horarios de 8:30 a 12:30 horas y de 17:00 a 19:00 horas.<\/p>\n<p>Este evento cultural, que re\u00fane la tradici\u00f3n de la danza cl\u00e1sica y espa\u00f1ola con la pasi\u00f3n del tango, invita a los vecinos de Mercedes a cerrar el a\u00f1o con un espect\u00e1culo de primer nivel.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-150143\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/8c82683d-0f27-46d2-9df1-6290ad5cfa4c.jpg\" alt=\"\" width=\"1080\" height=\"1080\" srcset=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/8c82683d-0f27-46d2-9df1-6290ad5cfa4c.jpg 1080w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/8c82683d-0f27-46d2-9df1-6290ad5cfa4c-300x300.jpg 300w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/8c82683d-0f27-46d2-9df1-6290ad5cfa4c-1024x1024.jpg 1024w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/8c82683d-0f27-46d2-9df1-6290ad5cfa4c-150x150.jpg 150w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/8c82683d-0f27-46d2-9df1-6290ad5cfa4c-768x768.jpg 768w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/8c82683d-0f27-46d2-9df1-6290ad5cfa4c-640x640.jpg 640w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/8c82683d-0f27-46d2-9df1-6290ad5cfa4c-681x681.jpg 681w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u25a0 Habr\u00e1 una imperdible Noche de Ballet, presentada por el Estudio de Danza Matilde Zetti de Asenzo bajo la direcci\u00f3n de la profesora Hayde\u00e9 Groba. Entradas en venta. Ser\u00e1 el s\u00e1bado 21 de diciembre<\/p>\n","protected":false},"author":16,"featured_media":150144,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[1813,2072,17725,163],"class_list":["post-150141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-ballet","tag-danzas","tag-haydee-groba","tag-teatro-argentino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El ballet se lucir\u00e1 con una noche de danza cl\u00e1sica y espa\u00f1ola<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasmercedinas.com\/site\/2024\/12\/10\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El ballet se lucir\u00e1 con una noche de danza cl\u00e1sica y espa\u00f1ola\" \/>\n<meta property=\"og:description\" content=\"\u25a0 Habr\u00e1 una imperdible Noche de Ballet, presentada por el Estudio de Danza Matilde Zetti de Asenzo bajo la direcci\u00f3n de la profesora Hayde\u00e9 Groba. Entradas en venta. Ser\u00e1 el s\u00e1bado 21 de diciembre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasmercedinas.com\/site\/2024\/12\/10\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\/\" \/>\n<meta property=\"og:site_name\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticiasmercedinas\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-10T12:52:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-10T18:46:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/125f7f3b-c947-4c3f-abac-e319032cbbe5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:site\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2024\\\/12\\\/10\\\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2024\\\/12\\\/10\\\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\\\/\"},\"author\":{\"name\":\"NOTICIASMERCEDINAS.COM\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/84b59c099c28ff2e8b77d4ceec5d8063\"},\"headline\":\"El ballet se lucir\u00e1 con una noche de danza cl\u00e1sica y espa\u00f1ola\",\"datePublished\":\"2024-12-10T12:52:35+00:00\",\"dateModified\":\"2024-12-10T18:46:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2024\\\/12\\\/10\\\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\\\/\"},\"wordCount\":207,\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2024\\\/12\\\/10\\\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/125f7f3b-c947-4c3f-abac-e319032cbbe5.jpg\",\"keywords\":[\"ballet\",\"danzas\",\"haydee groba\",\"teatro argentino\"],\"articleSection\":[\"Cultura\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2024\\\/12\\\/10\\\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2024\\\/12\\\/10\\\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\\\/\",\"name\":\"El ballet se lucir\u00e1 con una noche de danza cl\u00e1sica y espa\u00f1ola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2024\\\/12\\\/10\\\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2024\\\/12\\\/10\\\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/125f7f3b-c947-4c3f-abac-e319032cbbe5.jpg\",\"datePublished\":\"2024-12-10T12:52:35+00:00\",\"dateModified\":\"2024-12-10T18:46:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2024\\\/12\\\/10\\\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2024\\\/12\\\/10\\\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2024\\\/12\\\/10\\\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\\\/#primaryimage\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/125f7f3b-c947-4c3f-abac-e319032cbbe5.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/125f7f3b-c947-4c3f-abac-e319032cbbe5.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2024\\\/12\\\/10\\\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El ballet se lucir\u00e1 con una noche de danza cl\u00e1sica y espa\u00f1ola\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"description\":\"Mercedes, Buenos Aires, Argentina\",\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"width\":512,\"height\":512,\"caption\":\"NOTICIASMERCEDINAS.COM\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticiasmercedinas\\\/\",\"https:\\\/\\\/x.com\\\/notmercedinas\",\"https:\\\/\\\/www.instagram.com\\\/noticiasmercedinas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/84b59c099c28ff2e8b77d4ceec5d8063\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g\",\"caption\":\"NOTICIASMERCEDINAS.COM\"},\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/author\\\/anonimo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El ballet se lucir\u00e1 con una noche de danza cl\u00e1sica y espa\u00f1ola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasmercedinas.com\/site\/2024\/12\/10\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\/","og_locale":"es_ES","og_type":"article","og_title":"El ballet se lucir\u00e1 con una noche de danza cl\u00e1sica y espa\u00f1ola","og_description":"\u25a0 Habr\u00e1 una imperdible Noche de Ballet, presentada por el Estudio de Danza Matilde Zetti de Asenzo bajo la direcci\u00f3n de la profesora Hayde\u00e9 Groba. Entradas en venta. Ser\u00e1 el s\u00e1bado 21 de diciembre","og_url":"https:\/\/noticiasmercedinas.com\/site\/2024\/12\/10\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\/","og_site_name":"NOTICIASMERCEDINAS.COM","article_publisher":"https:\/\/www.facebook.com\/noticiasmercedinas\/","article_published_time":"2024-12-10T12:52:35+00:00","article_modified_time":"2024-12-10T18:46:37+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/125f7f3b-c947-4c3f-abac-e319032cbbe5.jpg","type":"image\/jpeg"}],"author":"NOTICIASMERCEDINAS.COM","twitter_card":"summary_large_image","twitter_creator":"@notmercedinas","twitter_site":"@notmercedinas","twitter_misc":{"Escrito por":"NOTICIASMERCEDINAS.COM","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasmercedinas.com\/site\/2024\/12\/10\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\/#article","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2024\/12\/10\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\/"},"author":{"name":"NOTICIASMERCEDINAS.COM","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/84b59c099c28ff2e8b77d4ceec5d8063"},"headline":"El ballet se lucir\u00e1 con una noche de danza cl\u00e1sica y espa\u00f1ola","datePublished":"2024-12-10T12:52:35+00:00","dateModified":"2024-12-10T18:46:37+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2024\/12\/10\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\/"},"wordCount":207,"publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2024\/12\/10\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/125f7f3b-c947-4c3f-abac-e319032cbbe5.jpg","keywords":["ballet","danzas","haydee groba","teatro argentino"],"articleSection":["Cultura"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasmercedinas.com\/site\/2024\/12\/10\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\/","url":"https:\/\/noticiasmercedinas.com\/site\/2024\/12\/10\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\/","name":"El ballet se lucir\u00e1 con una noche de danza cl\u00e1sica y espa\u00f1ola","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2024\/12\/10\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\/#primaryimage"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2024\/12\/10\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/125f7f3b-c947-4c3f-abac-e319032cbbe5.jpg","datePublished":"2024-12-10T12:52:35+00:00","dateModified":"2024-12-10T18:46:37+00:00","breadcrumb":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2024\/12\/10\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasmercedinas.com\/site\/2024\/12\/10\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/2024\/12\/10\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\/#primaryimage","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/125f7f3b-c947-4c3f-abac-e319032cbbe5.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2024\/12\/125f7f3b-c947-4c3f-abac-e319032cbbe5.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasmercedinas.com\/site\/2024\/12\/10\/el-ballet-se-lucira-con-una-noche-de-danza-clasica-y-espanola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noticiasmercedinas.com\/site\/"},{"@type":"ListItem","position":2,"name":"El ballet se lucir\u00e1 con una noche de danza cl\u00e1sica y espa\u00f1ola"}]},{"@type":"WebSite","@id":"https:\/\/noticiasmercedinas.com\/site\/#website","url":"https:\/\/noticiasmercedinas.com\/site\/","name":"NOTICIASMERCEDINAS.COM","description":"Mercedes, Buenos Aires, Argentina","publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasmercedinas.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasmercedinas.com\/site\/#organization","name":"NOTICIASMERCEDINAS.COM","url":"https:\/\/noticiasmercedinas.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","width":512,"height":512,"caption":"NOTICIASMERCEDINAS.COM"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticiasmercedinas\/","https:\/\/x.com\/notmercedinas","https:\/\/www.instagram.com\/noticiasmercedinas\/"]},{"@type":"Person","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/84b59c099c28ff2e8b77d4ceec5d8063","name":"NOTICIASMERCEDINAS.COM","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g","caption":"NOTICIASMERCEDINAS.COM"},"url":"https:\/\/noticiasmercedinas.com\/site\/author\/anonimo\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/150141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/comments?post=150141"}],"version-history":[{"count":2,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/150141\/revisions"}],"predecessor-version":[{"id":150168,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/150141\/revisions\/150168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media\/150144"}],"wp:attachment":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media?parent=150141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/categories?post=150141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/tags?post=150141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}