{"id":169020,"date":"2025-09-09T08:32:34","date_gmt":"2025-09-09T11:32:34","guid":{"rendered":"https:\/\/noticiasmercedinas.com\/site\/?p=169020"},"modified":"2025-09-09T08:33:13","modified_gmt":"2025-09-09T11:33:13","slug":"la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes","status":"publish","type":"post","link":"https:\/\/noticiasmercedinas.com\/site\/2025\/09\/09\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\/","title":{"rendered":"La Libertad Avanza celebra crecimiento electoral y conquista de nuevas bancas en Mercedes"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-169021\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/09\/imagen_2025-09-09_082627559.png\" alt=\"\" width=\"580\" height=\"434\" srcset=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/09\/imagen_2025-09-09_082627559.png 580w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/09\/imagen_2025-09-09_082627559-300x224.png 300w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/09\/imagen_2025-09-09_082627559-80x60.png 80w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/09\/imagen_2025-09-09_082627559-160x120.png 160w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/09\/imagen_2025-09-09_082627559-100x75.png 100w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/09\/imagen_2025-09-09_082627559-200x150.png 200w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/09\/imagen_2025-09-09_082627559-180x135.png 180w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/09\/imagen_2025-09-09_082627559-360x270.png 360w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/09\/imagen_2025-09-09_082627559-238x178.png 238w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/09\/imagen_2025-09-09_082627559-476x356.png 476w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/p>\n<p>Con un total de cuatro esca\u00f1os obtenidos, La Libertad Avanza de Mercedes celebr\u00f3 un crecimiento significativo en su desempe\u00f1o electoral. La fuerza pol\u00edtica, que puso en juego varios puestos legislativos, consigui\u00f3 que tres de sus candidatos ingresaran al Concejo Deliberante y uno al Consejo Escolar, consolid\u00e1ndose como una de las principales fuerzas del distrito.<\/p>\n<p>Rafael Vel\u00e1zquez, coordinador de La Libertad Avanza en Mercedes, expres\u00f3 sus felicitaciones a los flamantes legisladores electos a trav\u00e9s de sus redes sociales. \u201cFelicitaciones a los nuevos concejales Marcela Munarriz, Marcos Vergara, Carolina Bessega, y la nueva consejera escolar Paula C\u00f3rdoba\u201d, escribi\u00f3. El dirigente tambi\u00e9n agradeci\u00f3 el trabajo del \u201cgran equipo\u201d, los fiscales y la militancia, asegurando que el esfuerzo y el trabajo dieron sus frutos y que el camino de la fuerza \u201cno termina ac\u00e1\u201d.<\/p>\n<p>La Juventud de La Libertad Avanza tambi\u00e9n se sum\u00f3 a las celebraciones, destacando la importancia de la victoria. \u201cHoy celebramos un triunfo que ilumina el camino de la libertad en nuestra ciudad\u201d, publicaron, felicitando a los nuevos representantes por haber conquistado \u201cla confianza de los mercedinos con ideas de cambio, transparencia y progreso real\u201d.<\/p>\n<blockquote><p>Los j\u00f3venes instan a los nuevos ediles a ser la \u201cvoz de quienes buscan menos Estado, m\u00e1s oportunidades y una educaci\u00f3n basada en el m\u00e9rito\u201d<\/p><\/blockquote>\n<p>La agrupaci\u00f3n juvenil interpret\u00f3 el resultado como \u201cun paso firme hacia una Mercedes m\u00e1s libre y pr\u00f3spera\u201d. En su mensaje, instaron a los nuevos ediles a ser la \u201cvoz de quienes buscan menos Estado, m\u00e1s oportunidades y una educaci\u00f3n basada en el m\u00e9rito\u201d. El comunicado concluy\u00f3 con un llamado a trabajar con \u201cvalent\u00eda\u201d, \u201cfiscalizar con rigor\u201d y \u201cconstruir junto a la gente\u201d.<\/p>\n<p>La victoria de La Libertad Avanza en Mercedes, que le otorga una representaci\u00f3n in\u00e9dita en el legislativo local, confirma el crecimiento de la fuerza a nivel nacional y provincial, y marca el inicio de una nueva etapa para el espacio en el distrito.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u25a0 Con la elecci\u00f3n de tres concejales y una consejera escolar, el coordinador Rafael Vel\u00e1zquez y la Juventud de La Libertad Avanza celebraron el \u201ctriunfo\u201d que consolida a la fuerza como un actor clave en la pol\u00edtica local.<\/p>\n","protected":false},"author":16,"featured_media":169021,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,20734],"tags":[20652,15388,16099],"class_list":["post-169020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-ultimo-momento","tag-eleccones-2025","tag-la-libertad-avanza","tag-rafael-velasquez"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Libertad Avanza celebra crecimiento electoral y conquista de nuevas bancas en Mercedes<\/title>\n<meta name=\"description\" content=\"Con la elecci\u00f3n de tres concejales y una consejera escolar, el coordinador Rafael Vel\u00e1zquez y la Juventud de La Libertad Avanza celebraron el \u201ctriunfo\u201d que consolida a la fuerza como un actor clave en la pol\u00edtica local.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasmercedinas.com\/site\/2025\/09\/09\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Libertad Avanza celebra crecimiento electoral y conquista de nuevas bancas en Mercedes\" \/>\n<meta property=\"og:description\" content=\"Con la elecci\u00f3n de tres concejales y una consejera escolar, el coordinador Rafael Vel\u00e1zquez y la Juventud de La Libertad Avanza celebraron el \u201ctriunfo\u201d que consolida a la fuerza como un actor clave en la pol\u00edtica local.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasmercedinas.com\/site\/2025\/09\/09\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\/\" \/>\n<meta property=\"og:site_name\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticiasmercedinas\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-09T11:32:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-09T11:33:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/09\/imagen_2025-09-09_082627559.png\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"434\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:site\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/09\\\/09\\\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/09\\\/09\\\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\\\/\"},\"author\":{\"name\":\"NOTICIASMERCEDINAS.COM\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/84b59c099c28ff2e8b77d4ceec5d8063\"},\"headline\":\"La Libertad Avanza celebra crecimiento electoral y conquista de nuevas bancas en Mercedes\",\"datePublished\":\"2025-09-09T11:32:34+00:00\",\"dateModified\":\"2025-09-09T11:33:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/09\\\/09\\\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\\\/\"},\"wordCount\":350,\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/09\\\/09\\\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/imagen_2025-09-09_082627559.png\",\"keywords\":[\"eleccones 2025\",\"la libertad avanza\",\"Rafael Velasquez\"],\"articleSection\":[\"Politica\",\"Ultimo momento\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/09\\\/09\\\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/09\\\/09\\\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\\\/\",\"name\":\"La Libertad Avanza celebra crecimiento electoral y conquista de nuevas bancas en Mercedes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/09\\\/09\\\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/09\\\/09\\\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/imagen_2025-09-09_082627559.png\",\"datePublished\":\"2025-09-09T11:32:34+00:00\",\"dateModified\":\"2025-09-09T11:33:13+00:00\",\"description\":\"Con la elecci\u00f3n de tres concejales y una consejera escolar, el coordinador Rafael Vel\u00e1zquez y la Juventud de La Libertad Avanza celebraron el \u201ctriunfo\u201d que consolida a la fuerza como un actor clave en la pol\u00edtica local.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/09\\\/09\\\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/09\\\/09\\\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/09\\\/09\\\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/imagen_2025-09-09_082627559.png\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/imagen_2025-09-09_082627559.png\",\"width\":580,\"height\":434},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/09\\\/09\\\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Libertad Avanza celebra crecimiento electoral y conquista de nuevas bancas en Mercedes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"description\":\"Mercedes, Buenos Aires, Argentina\",\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"width\":512,\"height\":512,\"caption\":\"NOTICIASMERCEDINAS.COM\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticiasmercedinas\\\/\",\"https:\\\/\\\/x.com\\\/notmercedinas\",\"https:\\\/\\\/www.instagram.com\\\/noticiasmercedinas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/84b59c099c28ff2e8b77d4ceec5d8063\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g\",\"caption\":\"NOTICIASMERCEDINAS.COM\"},\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/author\\\/anonimo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Libertad Avanza celebra crecimiento electoral y conquista de nuevas bancas en Mercedes","description":"Con la elecci\u00f3n de tres concejales y una consejera escolar, el coordinador Rafael Vel\u00e1zquez y la Juventud de La Libertad Avanza celebraron el \u201ctriunfo\u201d que consolida a la fuerza como un actor clave en la pol\u00edtica local.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasmercedinas.com\/site\/2025\/09\/09\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\/","og_locale":"es_ES","og_type":"article","og_title":"La Libertad Avanza celebra crecimiento electoral y conquista de nuevas bancas en Mercedes","og_description":"Con la elecci\u00f3n de tres concejales y una consejera escolar, el coordinador Rafael Vel\u00e1zquez y la Juventud de La Libertad Avanza celebraron el \u201ctriunfo\u201d que consolida a la fuerza como un actor clave en la pol\u00edtica local.","og_url":"https:\/\/noticiasmercedinas.com\/site\/2025\/09\/09\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\/","og_site_name":"NOTICIASMERCEDINAS.COM","article_publisher":"https:\/\/www.facebook.com\/noticiasmercedinas\/","article_published_time":"2025-09-09T11:32:34+00:00","article_modified_time":"2025-09-09T11:33:13+00:00","og_image":[{"width":580,"height":434,"url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/09\/imagen_2025-09-09_082627559.png","type":"image\/png"}],"author":"NOTICIASMERCEDINAS.COM","twitter_card":"summary_large_image","twitter_creator":"@notmercedinas","twitter_site":"@notmercedinas","twitter_misc":{"Escrito por":"NOTICIASMERCEDINAS.COM","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasmercedinas.com\/site\/2025\/09\/09\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\/#article","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2025\/09\/09\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\/"},"author":{"name":"NOTICIASMERCEDINAS.COM","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/84b59c099c28ff2e8b77d4ceec5d8063"},"headline":"La Libertad Avanza celebra crecimiento electoral y conquista de nuevas bancas en Mercedes","datePublished":"2025-09-09T11:32:34+00:00","dateModified":"2025-09-09T11:33:13+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2025\/09\/09\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\/"},"wordCount":350,"publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2025\/09\/09\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/09\/imagen_2025-09-09_082627559.png","keywords":["eleccones 2025","la libertad avanza","Rafael Velasquez"],"articleSection":["Politica","Ultimo momento"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasmercedinas.com\/site\/2025\/09\/09\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\/","url":"https:\/\/noticiasmercedinas.com\/site\/2025\/09\/09\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\/","name":"La Libertad Avanza celebra crecimiento electoral y conquista de nuevas bancas en Mercedes","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2025\/09\/09\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\/#primaryimage"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2025\/09\/09\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/09\/imagen_2025-09-09_082627559.png","datePublished":"2025-09-09T11:32:34+00:00","dateModified":"2025-09-09T11:33:13+00:00","description":"Con la elecci\u00f3n de tres concejales y una consejera escolar, el coordinador Rafael Vel\u00e1zquez y la Juventud de La Libertad Avanza celebraron el \u201ctriunfo\u201d que consolida a la fuerza como un actor clave en la pol\u00edtica local.","breadcrumb":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2025\/09\/09\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasmercedinas.com\/site\/2025\/09\/09\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/2025\/09\/09\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\/#primaryimage","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/09\/imagen_2025-09-09_082627559.png","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/09\/imagen_2025-09-09_082627559.png","width":580,"height":434},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasmercedinas.com\/site\/2025\/09\/09\/la-libertad-avanza-celebra-crecimiento-electoral-y-conquista-de-nuevas-bancas-en-mercedes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noticiasmercedinas.com\/site\/"},{"@type":"ListItem","position":2,"name":"La Libertad Avanza celebra crecimiento electoral y conquista de nuevas bancas en Mercedes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasmercedinas.com\/site\/#website","url":"https:\/\/noticiasmercedinas.com\/site\/","name":"NOTICIASMERCEDINAS.COM","description":"Mercedes, Buenos Aires, Argentina","publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasmercedinas.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasmercedinas.com\/site\/#organization","name":"NOTICIASMERCEDINAS.COM","url":"https:\/\/noticiasmercedinas.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","width":512,"height":512,"caption":"NOTICIASMERCEDINAS.COM"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticiasmercedinas\/","https:\/\/x.com\/notmercedinas","https:\/\/www.instagram.com\/noticiasmercedinas\/"]},{"@type":"Person","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/84b59c099c28ff2e8b77d4ceec5d8063","name":"NOTICIASMERCEDINAS.COM","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g","caption":"NOTICIASMERCEDINAS.COM"},"url":"https:\/\/noticiasmercedinas.com\/site\/author\/anonimo\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/169020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/comments?post=169020"}],"version-history":[{"count":2,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/169020\/revisions"}],"predecessor-version":[{"id":169023,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/169020\/revisions\/169023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media\/169021"}],"wp:attachment":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media?parent=169020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/categories?post=169020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/tags?post=169020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}