{"id":175789,"date":"2025-12-02T22:23:44","date_gmt":"2025-12-03T01:23:44","guid":{"rendered":"https:\/\/noticiasmercedinas.com\/site\/?p=175789"},"modified":"2025-12-02T22:23:44","modified_gmt":"2025-12-03T01:23:44","slug":"concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras","status":"publish","type":"post","link":"https:\/\/noticiasmercedinas.com\/site\/2025\/12\/02\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\/","title":{"rendered":"Concejales de La Libertad Avanza exigen presupuesto \u00abmoderno, sostenible y orientado a obras\u00bb"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-175790\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/12\/fccf3469-ae87-4527-804e-5c8ba27eeb16.jpeg\" alt=\"\" width=\"1280\" height=\"960\" srcset=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/12\/fccf3469-ae87-4527-804e-5c8ba27eeb16.jpeg 1280w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/12\/fccf3469-ae87-4527-804e-5c8ba27eeb16-300x225.jpeg 300w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/12\/fccf3469-ae87-4527-804e-5c8ba27eeb16-1024x768.jpeg 1024w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/12\/fccf3469-ae87-4527-804e-5c8ba27eeb16-768x576.jpeg 768w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/12\/fccf3469-ae87-4527-804e-5c8ba27eeb16-80x60.jpeg 80w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/12\/fccf3469-ae87-4527-804e-5c8ba27eeb16-160x120.jpeg 160w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/12\/fccf3469-ae87-4527-804e-5c8ba27eeb16-100x75.jpeg 100w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/12\/fccf3469-ae87-4527-804e-5c8ba27eeb16-200x150.jpeg 200w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/12\/fccf3469-ae87-4527-804e-5c8ba27eeb16-180x135.jpeg 180w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/12\/fccf3469-ae87-4527-804e-5c8ba27eeb16-360x270.jpeg 360w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/12\/fccf3469-ae87-4527-804e-5c8ba27eeb16-238x178.jpeg 238w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/12\/fccf3469-ae87-4527-804e-5c8ba27eeb16-476x356.jpeg 476w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/12\/fccf3469-ae87-4527-804e-5c8ba27eeb16-640x480.jpeg 640w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/12\/fccf3469-ae87-4527-804e-5c8ba27eeb16-681x511.jpeg 681w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>Los concejales de Mercedes por La Libertad Avanza, Silvia Di Leo y Mauricio Pollacchi, participaron en el Seminario Legislativo Nacional que nucle\u00f3 a referentes del espacio en Mar del Plata. Tras el c\u00f3nclave, la principal conclusi\u00f3n de los ediles se centr\u00f3 en la situaci\u00f3n econ\u00f3mica y fiscal del partido, donde Pollacchi, en un extenso an\u00e1lisis, reclam\u00f3 un \u00abpresupuesto moderno, sostenible y orientado a las obras\u00bb para 2026 y una urgente reforma del sistema tributario local, el cual considera que ha sobrecargado a los contribuyentes.<\/p>\n<p>El concejal de LLA profundiz\u00f3 en la visi\u00f3n del bloque respecto al proyecto de Presupuesto y la Ordenanza Fiscal Impositiva para el pr\u00f3ximo ejercicio. Si bien reconoci\u00f3 que el presupuesto 2026 no presenta d\u00e9ficit y el Municipio cubre funciones que competen a la Provincia, fue enf\u00e1tico en se\u00f1alar que \u00abel dise\u00f1o actual no permite proyectar obras esenciales \u2014como pavimento o cloacas\u2014 sin aportes externos espec\u00edficos.\u00bb<\/p>\n<p>Pollacchi observ\u00f3 con preocupaci\u00f3n que el proyecto presentado es \u00abpr\u00e1cticamente id\u00e9ntico a los de 2024 y 2025,\u00bb con la sola diferencia del ajuste por inflaci\u00f3n. Aunque admiti\u00f3 una \u00abmayor razonabilidad respecto a ejercicios anteriores,\u00bb no detect\u00f3 un \u00abcambio real en la definici\u00f3n de prioridades\u00bb ni un fortalecimiento de \u00e1reas estrat\u00e9gicas.<\/p>\n<p>\u00abNo vemos un cambio real en la definici\u00f3n de prioridades: no hay un fortalecimiento de \u00e1reas estrat\u00e9gicas, ni una planificaci\u00f3n que oriente recursos hacia obra p\u00fablica, producci\u00f3n o desarrollo local. Por eso creemos necesario avanzar hacia un esquema m\u00e1s eficiente, con prioridades claras y capacidad de inversi\u00f3n real,\u00bb sostuvo el concejal.<\/p>\n<p>El edil destac\u00f3 la necesidad de que Mercedes \u00abrecupere un presupuesto capaz de impulsar obras con fondos propios y consolidar un desarrollo sostenido.\u00bb Si bien la dependencia de recursos nacionales en el pasado permiti\u00f3 el crecimiento de la estructura municipal, hoy exige \u00abrepensar c\u00f3mo financiamos y garantizamos los servicios sin sobrecargar a los vecinos.\u00bb<\/p>\n<p>En cuanto a la fiscal impositiva, el bloque libertario enfatiz\u00f3 la urgencia de construir un \u00absistema m\u00e1s equitativo, m\u00e1s simple, m\u00e1s justo y m\u00e1s transparente\u00bb. Pollacchi puntualiz\u00f3 que las valuaciones fiscales dispares generan distorsiones que afectan tanto a vecinos como a comerciantes, por lo que el esquema basado en valuaciones debe ser reemplazado.<\/p>\n<p>Otro punto de an\u00e1lisis fue el comercio local, donde el concejal advirti\u00f3 sobre el impacto del aumento de la bancarizaci\u00f3n (con solo un 25% de ventas en efectivo), lo que \u00abincrementa la cantidad de operaciones alcanzadas por tributos.\u00bb<\/p>\n<p>\u00abEl comercio local tambi\u00e9n cambi\u00f3&#8230; Creemos importante realizar un an\u00e1lisis detallado del impacto real sobre el sector y evaluar mecanismos que acompa\u00f1en a quienes sostienen la actividad econ\u00f3mica de la ciudad,\u00bb remarc\u00f3.<\/p>\n<p>Pollacchi cit\u00f3 que los \u00edndices de cobrabilidad de las tasas municipales rondan apenas el 30%, una cifra que para el bloque evidencia que el sistema requiere \u00abmejoras urgentes\u00bb. Para el concejal, un esquema m\u00e1s claro y eficiente no solo aliviar\u00eda al contribuyente, sino que tambi\u00e9n permitir\u00eda al Estado municipal \u00abrecaudar mejor y planificar obras y servicios con mayor autonom\u00eda.\u00bb<\/p>\n<p>El concejal tambi\u00e9n mencion\u00f3 que muchos vecinos han sufrido aumentos superiores al 500% en poco tiempo, lo que obliga a revisar los criterios tributarios. Finalmente, si bien el Municipio planea un aumento del 20% en enero de 2026 m\u00e1s actualizaciones bimestrales por inflaci\u00f3n, Pollacchi concluy\u00f3 que \u00abantes de seguir ajustando sobre los contribuyentes creemos que es necesario abordar las causas estructurales que nos trajeron hasta ac\u00e1 y trabajar en soluciones de fondo.\u00bb<\/p>\n<p>El objetivo final del espacio es \u00abconstruir una ciudad con m\u00e1s desarrollo, m\u00e1s oportunidades y un crecimiento equilibrado para todos,\u00bb fomentando las inversiones privadas y ampliando la base tributaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u25a0 Mauricio Pollacchi y Silvia Di Leo, tras asistir al Seminario Legislativo en Mar del Plata, criticaron el proyecto presupuestario 2026 de Mercedes, se\u00f1alando la falta de prioridades estrat\u00e9gicas y la necesidad de una reforma tributaria \u00abm\u00e1s justa\u00bb y con mayor capacidad de inversi\u00f3n. Piden un sistema que alivie la presi\u00f3n sobre los vecinos.<\/p>\n","protected":false},"author":16,"featured_media":175790,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[15388,8739,21323,14622],"class_list":["post-175789","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-la-libertad-avanza","tag-mauricio-pollacchi","tag-presupuesto-2026","tag-silvia-di-leo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Concejales de La Libertad Avanza exigen presupuesto &quot;moderno, sostenible y orientado a obras&quot;<\/title>\n<meta name=\"description\" content=\"\u25a0 Mauricio Pollacchi y Silvia Di Leo, tras asistir al Seminario Legislativo en Mar del Plata, criticaron el proyecto presupuestario 2026 de Mercedes, se\u00f1alando la falta de prioridades estrat\u00e9gicas y la necesidad de una reforma tributaria &quot;m\u00e1s justa&quot; y con mayor capacidad de inversi\u00f3n. Piden un sistema que alivie la presi\u00f3n sobre los vecinos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasmercedinas.com\/site\/2025\/12\/02\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concejales de La Libertad Avanza exigen presupuesto &quot;moderno, sostenible y orientado a obras&quot;\" \/>\n<meta property=\"og:description\" content=\"\u25a0 Mauricio Pollacchi y Silvia Di Leo, tras asistir al Seminario Legislativo en Mar del Plata, criticaron el proyecto presupuestario 2026 de Mercedes, se\u00f1alando la falta de prioridades estrat\u00e9gicas y la necesidad de una reforma tributaria &quot;m\u00e1s justa&quot; y con mayor capacidad de inversi\u00f3n. Piden un sistema que alivie la presi\u00f3n sobre los vecinos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasmercedinas.com\/site\/2025\/12\/02\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\/\" \/>\n<meta property=\"og:site_name\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticiasmercedinas\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-03T01:23:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/12\/fccf3469-ae87-4527-804e-5c8ba27eeb16.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:site\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/12\\\/02\\\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/12\\\/02\\\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\\\/\"},\"author\":{\"name\":\"NOTICIASMERCEDINAS.COM\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/84b59c099c28ff2e8b77d4ceec5d8063\"},\"headline\":\"Concejales de La Libertad Avanza exigen presupuesto \u00abmoderno, sostenible y orientado a obras\u00bb\",\"datePublished\":\"2025-12-03T01:23:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/12\\\/02\\\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\\\/\"},\"wordCount\":637,\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/12\\\/02\\\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/fccf3469-ae87-4527-804e-5c8ba27eeb16.jpeg\",\"keywords\":[\"la libertad avanza\",\"mauricio pollacchi\",\"presupuesto 2026\",\"Silvia Di Leo\"],\"articleSection\":[\"Politica\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/12\\\/02\\\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/12\\\/02\\\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\\\/\",\"name\":\"Concejales de La Libertad Avanza exigen presupuesto \\\"moderno, sostenible y orientado a obras\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/12\\\/02\\\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/12\\\/02\\\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/fccf3469-ae87-4527-804e-5c8ba27eeb16.jpeg\",\"datePublished\":\"2025-12-03T01:23:44+00:00\",\"description\":\"\u25a0 Mauricio Pollacchi y Silvia Di Leo, tras asistir al Seminario Legislativo en Mar del Plata, criticaron el proyecto presupuestario 2026 de Mercedes, se\u00f1alando la falta de prioridades estrat\u00e9gicas y la necesidad de una reforma tributaria \\\"m\u00e1s justa\\\" y con mayor capacidad de inversi\u00f3n. Piden un sistema que alivie la presi\u00f3n sobre los vecinos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/12\\\/02\\\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/12\\\/02\\\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/12\\\/02\\\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/fccf3469-ae87-4527-804e-5c8ba27eeb16.jpeg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/fccf3469-ae87-4527-804e-5c8ba27eeb16.jpeg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2025\\\/12\\\/02\\\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concejales de La Libertad Avanza exigen presupuesto \u00abmoderno, sostenible y orientado a obras\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"description\":\"Mercedes, Buenos Aires, Argentina\",\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"width\":512,\"height\":512,\"caption\":\"NOTICIASMERCEDINAS.COM\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticiasmercedinas\\\/\",\"https:\\\/\\\/x.com\\\/notmercedinas\",\"https:\\\/\\\/www.instagram.com\\\/noticiasmercedinas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/84b59c099c28ff2e8b77d4ceec5d8063\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g\",\"caption\":\"NOTICIASMERCEDINAS.COM\"},\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/author\\\/anonimo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Concejales de La Libertad Avanza exigen presupuesto \"moderno, sostenible y orientado a obras\"","description":"\u25a0 Mauricio Pollacchi y Silvia Di Leo, tras asistir al Seminario Legislativo en Mar del Plata, criticaron el proyecto presupuestario 2026 de Mercedes, se\u00f1alando la falta de prioridades estrat\u00e9gicas y la necesidad de una reforma tributaria \"m\u00e1s justa\" y con mayor capacidad de inversi\u00f3n. Piden un sistema que alivie la presi\u00f3n sobre los vecinos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasmercedinas.com\/site\/2025\/12\/02\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\/","og_locale":"es_ES","og_type":"article","og_title":"Concejales de La Libertad Avanza exigen presupuesto \"moderno, sostenible y orientado a obras\"","og_description":"\u25a0 Mauricio Pollacchi y Silvia Di Leo, tras asistir al Seminario Legislativo en Mar del Plata, criticaron el proyecto presupuestario 2026 de Mercedes, se\u00f1alando la falta de prioridades estrat\u00e9gicas y la necesidad de una reforma tributaria \"m\u00e1s justa\" y con mayor capacidad de inversi\u00f3n. Piden un sistema que alivie la presi\u00f3n sobre los vecinos.","og_url":"https:\/\/noticiasmercedinas.com\/site\/2025\/12\/02\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\/","og_site_name":"NOTICIASMERCEDINAS.COM","article_publisher":"https:\/\/www.facebook.com\/noticiasmercedinas\/","article_published_time":"2025-12-03T01:23:44+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/12\/fccf3469-ae87-4527-804e-5c8ba27eeb16.jpeg","type":"image\/jpeg"}],"author":"NOTICIASMERCEDINAS.COM","twitter_card":"summary_large_image","twitter_creator":"@notmercedinas","twitter_site":"@notmercedinas","twitter_misc":{"Escrito por":"NOTICIASMERCEDINAS.COM","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasmercedinas.com\/site\/2025\/12\/02\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\/#article","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2025\/12\/02\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\/"},"author":{"name":"NOTICIASMERCEDINAS.COM","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/84b59c099c28ff2e8b77d4ceec5d8063"},"headline":"Concejales de La Libertad Avanza exigen presupuesto \u00abmoderno, sostenible y orientado a obras\u00bb","datePublished":"2025-12-03T01:23:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2025\/12\/02\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\/"},"wordCount":637,"publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2025\/12\/02\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/12\/fccf3469-ae87-4527-804e-5c8ba27eeb16.jpeg","keywords":["la libertad avanza","mauricio pollacchi","presupuesto 2026","Silvia Di Leo"],"articleSection":["Politica"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasmercedinas.com\/site\/2025\/12\/02\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\/","url":"https:\/\/noticiasmercedinas.com\/site\/2025\/12\/02\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\/","name":"Concejales de La Libertad Avanza exigen presupuesto \"moderno, sostenible y orientado a obras\"","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2025\/12\/02\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\/#primaryimage"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2025\/12\/02\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/12\/fccf3469-ae87-4527-804e-5c8ba27eeb16.jpeg","datePublished":"2025-12-03T01:23:44+00:00","description":"\u25a0 Mauricio Pollacchi y Silvia Di Leo, tras asistir al Seminario Legislativo en Mar del Plata, criticaron el proyecto presupuestario 2026 de Mercedes, se\u00f1alando la falta de prioridades estrat\u00e9gicas y la necesidad de una reforma tributaria \"m\u00e1s justa\" y con mayor capacidad de inversi\u00f3n. Piden un sistema que alivie la presi\u00f3n sobre los vecinos.","breadcrumb":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2025\/12\/02\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasmercedinas.com\/site\/2025\/12\/02\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/2025\/12\/02\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\/#primaryimage","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/12\/fccf3469-ae87-4527-804e-5c8ba27eeb16.jpeg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2025\/12\/fccf3469-ae87-4527-804e-5c8ba27eeb16.jpeg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasmercedinas.com\/site\/2025\/12\/02\/concejales-de-la-libertad-avanza-exigen-presupuesto-moderno-sostenible-y-orientado-a-obras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noticiasmercedinas.com\/site\/"},{"@type":"ListItem","position":2,"name":"Concejales de La Libertad Avanza exigen presupuesto \u00abmoderno, sostenible y orientado a obras\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/noticiasmercedinas.com\/site\/#website","url":"https:\/\/noticiasmercedinas.com\/site\/","name":"NOTICIASMERCEDINAS.COM","description":"Mercedes, Buenos Aires, Argentina","publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasmercedinas.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasmercedinas.com\/site\/#organization","name":"NOTICIASMERCEDINAS.COM","url":"https:\/\/noticiasmercedinas.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","width":512,"height":512,"caption":"NOTICIASMERCEDINAS.COM"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticiasmercedinas\/","https:\/\/x.com\/notmercedinas","https:\/\/www.instagram.com\/noticiasmercedinas\/"]},{"@type":"Person","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/84b59c099c28ff2e8b77d4ceec5d8063","name":"NOTICIASMERCEDINAS.COM","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g","caption":"NOTICIASMERCEDINAS.COM"},"url":"https:\/\/noticiasmercedinas.com\/site\/author\/anonimo\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/175789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/comments?post=175789"}],"version-history":[{"count":1,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/175789\/revisions"}],"predecessor-version":[{"id":175791,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/175789\/revisions\/175791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media\/175790"}],"wp:attachment":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media?parent=175789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/categories?post=175789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/tags?post=175789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}