{"id":183476,"date":"2026-04-06T02:06:03","date_gmt":"2026-04-06T05:06:03","guid":{"rendered":"https:\/\/noticiasmercedinas.com\/site\/?p=183476"},"modified":"2026-04-06T02:06:03","modified_gmt":"2026-04-06T05:06:03","slug":"lo-que-dejo-el-domingo-con-interzonales-y-zona-c","status":"publish","type":"post","link":"https:\/\/noticiasmercedinas.com\/site\/2026\/04\/06\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\/","title":{"rendered":"Lo que dej\u00f3 el domingo con interzonales y Zona C"},"content":{"rendered":"<figure id=\"attachment_183477\" aria-describedby=\"caption-attachment-183477\" style=\"width: 640px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-183477 size-full\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/04\/IMG_9735.jpg\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/04\/IMG_9735.jpg 640w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/04\/IMG_9735-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-183477\" class=\"wp-caption-text\">Estudiantes.<\/figcaption><\/figure>\n<p>Luego del empate 2-2 de El Front\u00f3n y Villa Manchi m\u00e1s los suspendidos del s\u00e1bado 4, este domingo 5 la Liga Mercedina de F\u00fatbol centr\u00f3 su actividad en su propia cancha con cuatro partidos m\u00e1s los que sucedi\u00f3 en J\u00e1uregui y el V\u00edctor Cestari.\u00a0 De esta manera la Zona C cumpli\u00f3 con se cuarta fecha donde V\u00e9lez fue el libre, todos los dem\u00e1s encuentros resultaron ser interzonales entre conjuntos de los grupos A y B.<\/p>\n<p>El que gan\u00f3 su primer partido del Apertura es Palometas, tras un primer tiempo sin goles lleg\u00f3 a tres conquistas y con ello construye una campa\u00f1a de menor a mayor. Por su parte Holanda sigue sin encontrar el rumbo correcto. El que marcha por la senda del triunfo de Juventud, gan\u00e1ndole en la noche del domingo a Jorge Newbery, los de Suipacha adeudan un juego mientras que el equipo de Luj\u00e1n ha vuelto a tropezar.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-183478\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/04\/IMG_9069.jpg\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/04\/IMG_9069.jpg 640w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/04\/IMG_9069-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>En el V\u00edctor Cestari tambi\u00e9n hubo f\u00fatbol, el 1 a 1 empezaba a marcar el cierre de partido hasta que en el adicional Ateneo se puso 2-1 sobre All Haz \u00a0y con ello logr\u00f3 reponerse el equipo de Amed que adeuda el partido con Holanda por la tercera fecha. Debut no deseado para el club que adeuda dos encuentros y ya qued\u00f3 libre, tendr\u00e1 que visitar a Juventud en Suipacha y medirse frente a Jorge Newbery.<\/p>\n<p>A la hora de los interzonales, entre las zonas A y B, abundaron los empates y casualmente todos fueron 2 a 2. Con ese marcador Estudiantes sigue siendo puntero en su grupo y el que salt\u00f3 a lo alto de Carteros. El otro reparto de puntos dej\u00f3 a Quilmes con su primera unidad, engrosando la suma de la tabla Defensores. Por \u00faltimo, Pabell\u00f3n se hizo del primer triunfo en su paso por J\u00e1uregui. Tim\u00f3n no logra salir de la serie de resultados negativos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-183479\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/04\/IMG_9342.jpg\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/04\/IMG_9342.jpg 640w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/04\/IMG_9342-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><br \/>\n<strong>Zona C<\/strong><br \/>\n<strong>Palometas 3:<\/strong> Valent\u00edn Russi 2 y Angel Far\u00edas.<br \/>\n<strong>Holanda 0.<br \/>\nArbitro<\/strong>: Cristian Sgro (CADEP).<\/p>\n<p><strong>Jorge Newbery 0.<br \/>\n<\/strong><strong>Juventud 2<\/strong>: Mat\u00edas Correa y Jos\u00e9 Perruiset.<br \/>\n<strong>Arbitro:<\/strong> Joaqu\u00edn Valenzuela (AMAI).<\/p>\n<p><strong>Ateneo 2:<\/strong> Lautaro Mart\u00ednez 2.<br \/>\n<strong>All Haz 1:<\/strong> Lautaro Valiente.<br \/>\n<strong>Arbitro:<\/strong> Germ\u00e1n Gauna (AMAI).<strong><\/p>\n<p>Interzonales<br \/>\nCarteros 2<\/strong>: Blas De Los Santos y Marcos Camargo.<br \/>\n<strong>Estudiantes 2:<\/strong> Juan Dell Oro y Juli\u00e1n Ag\u00fcero (EC).<br \/>\n<strong>Arbitro:<\/strong> Rom\u00e1n Grande.<\/p>\n<p><strong>Defensores 2:<\/strong> Agust\u00edn Villalba y Braian S\u00e1nchez.<br \/>\n<strong>Quilmes 2:<\/strong> Guzm\u00e1n y Ciancio.<br \/>\n<strong>Arbitro:<\/strong> Luis L\u00f3pez (AAM).<\/p>\n<p><strong>El Tim\u00f3n 1:<\/strong> Juan Lagrecca.<br \/>\n<strong>Pabell\u00f3n Argentino 4:<\/strong> Andr\u00e9s Olveira, Juan Paulerena, Benjam\u00edn Acosta y Nahuel Romero.<br \/>\n<strong>Arbitro:<\/strong> Emanuel S\u00e1nchez (CAM).<\/p>\n<p><strong>Suspendidos<\/strong><br \/>\nClub Mercedes vs. Trocha.<br \/>\nUni\u00f3n vs. AMEFIP.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-183480\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/04\/Primera-2026-1.jpg\" alt=\"\" width=\"640\" height=\"570\" srcset=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/04\/Primera-2026-1.jpg 640w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/04\/Primera-2026-1-300x267.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><strong>Pr\u00f3xima fecha<br \/>\nZona A<br \/>\n<\/strong>Estudiantes vs. Club Mercedes.<br \/>\nAMEFIP vs. El Tim\u00f3n.<br \/>\nVilla Manchi vs. Defensores Juniors.<\/p>\n<p><strong>Zona B<\/strong><br \/>\nTrocha vs. El Front\u00f3n.<br \/>\nPabell\u00f3n vs. Carteros.<br \/>\nQuilmes vs. Uni\u00f3n.<\/p>\n<p><strong>Zona C<br \/>\n<\/strong>Juventud vs. Ateneo.<br \/>\nAll Haz vs. Palometas.<br \/>\nHolanda vs. V\u00e9lez.<br \/>\n<strong>Libre:<\/strong> Jorge Newbery.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u25a0 Empataron Carteros y Estudiantes para darse lo mismo entre Quilmes frente a Defensores. El ganador fue Pabell\u00f3n en los cruces de las zonas A y B. En la cuarta jornada de al C Palometas, Juventud y Ateneo sumaron de a tres.<\/p>\n","protected":false},"author":6,"featured_media":183477,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[3346,14140],"class_list":["post-183476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-liga-mercedina-de-futbol","tag-primera-division-a"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lo que dej\u00f3 el domingo con interzonales y Zona C<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasmercedinas.com\/site\/2026\/04\/06\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo que dej\u00f3 el domingo con interzonales y Zona C\" \/>\n<meta property=\"og:description\" content=\"\u25a0 Empataron Carteros y Estudiantes para darse lo mismo entre Quilmes frente a Defensores. El ganador fue Pabell\u00f3n en los cruces de las zonas A y B. En la cuarta jornada de al C Palometas, Juventud y Ateneo sumaron de a tres.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasmercedinas.com\/site\/2026\/04\/06\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\/\" \/>\n<meta property=\"og:site_name\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticiasmercedinas\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-06T05:06:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/04\/IMG_9735.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juan Dagnino NOTICIASMERCEDINAS.COM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:site\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Dagnino NOTICIASMERCEDINAS.COM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/04\\\/06\\\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/04\\\/06\\\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\\\/\"},\"author\":{\"name\":\"Juan Dagnino NOTICIASMERCEDINAS.COM\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/8f2f09d666ef40986eba4a5e6f2a06f9\"},\"headline\":\"Lo que dej\u00f3 el domingo con interzonales y Zona C\",\"datePublished\":\"2026-04-06T05:06:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/04\\\/06\\\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\\\/\"},\"wordCount\":505,\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/04\\\/06\\\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/IMG_9735.jpg\",\"keywords\":[\"Liga Mercedina de F\u00fatbol\",\"primera divisi\u00f3n a\"],\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/04\\\/06\\\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/04\\\/06\\\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\\\/\",\"name\":\"Lo que dej\u00f3 el domingo con interzonales y Zona C\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/04\\\/06\\\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/04\\\/06\\\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/IMG_9735.jpg\",\"datePublished\":\"2026-04-06T05:06:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/04\\\/06\\\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/04\\\/06\\\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/04\\\/06\\\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\\\/#primaryimage\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/IMG_9735.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/IMG_9735.jpg\",\"width\":640,\"height\":427},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/04\\\/06\\\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lo que dej\u00f3 el domingo con interzonales y Zona C\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"description\":\"Mercedes, Buenos Aires, Argentina\",\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"width\":512,\"height\":512,\"caption\":\"NOTICIASMERCEDINAS.COM\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticiasmercedinas\\\/\",\"https:\\\/\\\/x.com\\\/notmercedinas\",\"https:\\\/\\\/www.instagram.com\\\/noticiasmercedinas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/8f2f09d666ef40986eba4a5e6f2a06f9\",\"name\":\"Juan Dagnino NOTICIASMERCEDINAS.COM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc7059a769f5a3cae65fadb228a3e4accf3a64b4b2305020d0a27e6d5333c91b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc7059a769f5a3cae65fadb228a3e4accf3a64b4b2305020d0a27e6d5333c91b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc7059a769f5a3cae65fadb228a3e4accf3a64b4b2305020d0a27e6d5333c91b?s=96&d=mm&r=g\",\"caption\":\"Juan Dagnino NOTICIASMERCEDINAS.COM\"},\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/author\\\/juandagnino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo que dej\u00f3 el domingo con interzonales y Zona C","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasmercedinas.com\/site\/2026\/04\/06\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\/","og_locale":"es_ES","og_type":"article","og_title":"Lo que dej\u00f3 el domingo con interzonales y Zona C","og_description":"\u25a0 Empataron Carteros y Estudiantes para darse lo mismo entre Quilmes frente a Defensores. El ganador fue Pabell\u00f3n en los cruces de las zonas A y B. En la cuarta jornada de al C Palometas, Juventud y Ateneo sumaron de a tres.","og_url":"https:\/\/noticiasmercedinas.com\/site\/2026\/04\/06\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\/","og_site_name":"NOTICIASMERCEDINAS.COM","article_publisher":"https:\/\/www.facebook.com\/noticiasmercedinas\/","article_published_time":"2026-04-06T05:06:03+00:00","og_image":[{"width":640,"height":427,"url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/04\/IMG_9735.jpg","type":"image\/jpeg"}],"author":"Juan Dagnino NOTICIASMERCEDINAS.COM","twitter_card":"summary_large_image","twitter_creator":"@notmercedinas","twitter_site":"@notmercedinas","twitter_misc":{"Escrito por":"Juan Dagnino NOTICIASMERCEDINAS.COM","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasmercedinas.com\/site\/2026\/04\/06\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\/#article","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2026\/04\/06\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\/"},"author":{"name":"Juan Dagnino NOTICIASMERCEDINAS.COM","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/8f2f09d666ef40986eba4a5e6f2a06f9"},"headline":"Lo que dej\u00f3 el domingo con interzonales y Zona C","datePublished":"2026-04-06T05:06:03+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2026\/04\/06\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\/"},"wordCount":505,"publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2026\/04\/06\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/04\/IMG_9735.jpg","keywords":["Liga Mercedina de F\u00fatbol","primera divisi\u00f3n a"],"articleSection":["Deportes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasmercedinas.com\/site\/2026\/04\/06\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\/","url":"https:\/\/noticiasmercedinas.com\/site\/2026\/04\/06\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\/","name":"Lo que dej\u00f3 el domingo con interzonales y Zona C","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2026\/04\/06\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\/#primaryimage"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2026\/04\/06\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/04\/IMG_9735.jpg","datePublished":"2026-04-06T05:06:03+00:00","breadcrumb":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2026\/04\/06\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasmercedinas.com\/site\/2026\/04\/06\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/2026\/04\/06\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\/#primaryimage","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/04\/IMG_9735.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/04\/IMG_9735.jpg","width":640,"height":427},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasmercedinas.com\/site\/2026\/04\/06\/lo-que-dejo-el-domingo-con-interzonales-y-zona-c\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noticiasmercedinas.com\/site\/"},{"@type":"ListItem","position":2,"name":"Lo que dej\u00f3 el domingo con interzonales y Zona C"}]},{"@type":"WebSite","@id":"https:\/\/noticiasmercedinas.com\/site\/#website","url":"https:\/\/noticiasmercedinas.com\/site\/","name":"NOTICIASMERCEDINAS.COM","description":"Mercedes, Buenos Aires, Argentina","publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasmercedinas.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasmercedinas.com\/site\/#organization","name":"NOTICIASMERCEDINAS.COM","url":"https:\/\/noticiasmercedinas.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","width":512,"height":512,"caption":"NOTICIASMERCEDINAS.COM"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticiasmercedinas\/","https:\/\/x.com\/notmercedinas","https:\/\/www.instagram.com\/noticiasmercedinas\/"]},{"@type":"Person","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/8f2f09d666ef40986eba4a5e6f2a06f9","name":"Juan Dagnino NOTICIASMERCEDINAS.COM","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fc7059a769f5a3cae65fadb228a3e4accf3a64b4b2305020d0a27e6d5333c91b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fc7059a769f5a3cae65fadb228a3e4accf3a64b4b2305020d0a27e6d5333c91b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fc7059a769f5a3cae65fadb228a3e4accf3a64b4b2305020d0a27e6d5333c91b?s=96&d=mm&r=g","caption":"Juan Dagnino NOTICIASMERCEDINAS.COM"},"url":"https:\/\/noticiasmercedinas.com\/site\/author\/juandagnino\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/183476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/comments?post=183476"}],"version-history":[{"count":1,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/183476\/revisions"}],"predecessor-version":[{"id":183481,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/183476\/revisions\/183481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media\/183477"}],"wp:attachment":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media?parent=183476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/categories?post=183476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/tags?post=183476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}