{"id":186359,"date":"2026-05-13T09:56:43","date_gmt":"2026-05-13T12:56:43","guid":{"rendered":"https:\/\/noticiasmercedinas.com\/site\/?p=186359"},"modified":"2026-05-13T09:56:43","modified_gmt":"2026-05-13T12:56:43","slug":"club-mercedes-comenzo-su-participacion-en-el-federacion-norte","status":"publish","type":"post","link":"https:\/\/noticiasmercedinas.com\/site\/2026\/05\/13\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\/","title":{"rendered":"Club Mercedes comenz\u00f3 su participaci\u00f3n en el Federaci\u00f3n Norte"},"content":{"rendered":"<p>Durante la noche del \u00faltimo martes 12 en el predio de H\u00e9roes de Malvinas y calle 60 se jugaron los partidos de la primera fecha por la Zona D del Torneo Juvenil de la Federaci\u00f3n Norte de F\u00fatbol. Recibiendo Club Mercedes a 9 de Julio Chacabuco.<\/p>\n<p>El \u201cBlanquinegro\u201d alcanz\u00f3 victorias en las categor\u00edas Sub 17 y Sub 15, teniendo un traspi\u00e9 en la Sub 13. De esta manera qued\u00f3 culminada la primera fecha donde ya afrontaron sus partidos Compa\u00f1\u00eda vs. Palometas y Argentino vs. Col\u00f3n.<\/p>\n<p><strong>Sub 17<\/strong><br \/>\nClub Mercedes 3 (Lucero, Chidichimo y Ustarroz) \u2013 9 de Julio de Chacabuco 2.<\/p>\n<p><strong>Sub 15<\/strong><br \/>\nClub Mercedes 1 (Casaretto) \u2013 9 de Julio Chacabuco 0.<\/p>\n<p><strong>Sub 13<\/strong><br \/>\nClub Mercedes 0 \u2013 9 de Julio de Chacabuco 2.<\/p>\n<p><strong>Pr\u00f3xima fecha<\/strong><br \/>\nCol\u00f3n (Chivilcoy) vs. 9 de Julio (Chacabuco).<br \/>\nPalometas FC vs. Club Mercedes.<br \/>\nArgentino (Chacabuco) vs. Compa\u00f1\u00eda General (Salto).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u25a0 Anoche en su predio tuvo la visita de 9 de Julio de Chacabuco. El local gan\u00f3 en las categor\u00edas Su 17 y Sub 15 quedando el resultado para la visita en Sub 13.  La pr\u00f3xima semana se jugar\u00e1 la segunda fecha.<\/p>\n","protected":false},"author":6,"featured_media":186360,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[22167,135,530,4422,5542,3410],"class_list":["post-186359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-9-de-julio-chacabuco","tag-club-mercedes","tag-sub-13","tag-sub-15","tag-sub-17","tag-torneo-federacion-norte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Club Mercedes comenz\u00f3 su participaci\u00f3n en el Federaci\u00f3n Norte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasmercedinas.com\/site\/2026\/05\/13\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Club Mercedes comenz\u00f3 su participaci\u00f3n en el Federaci\u00f3n Norte\" \/>\n<meta property=\"og:description\" content=\"\u25a0 Anoche en su predio tuvo la visita de 9 de Julio de Chacabuco. El local gan\u00f3 en las categor\u00edas Su 17 y Sub 15 quedando el resultado para la visita en Sub 13. La pr\u00f3xima semana se jugar\u00e1 la segunda fecha.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasmercedinas.com\/site\/2026\/05\/13\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\/\" \/>\n<meta property=\"og:site_name\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticiasmercedinas\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T12:56:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/05\/pelota-kagiva-campo-oficial-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"454\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juan Dagnino NOTICIASMERCEDINAS.COM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:site\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Dagnino NOTICIASMERCEDINAS.COM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/05\\\/13\\\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/05\\\/13\\\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\\\/\"},\"author\":{\"name\":\"Juan Dagnino NOTICIASMERCEDINAS.COM\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/8f2f09d666ef40986eba4a5e6f2a06f9\"},\"headline\":\"Club Mercedes comenz\u00f3 su participaci\u00f3n en el Federaci\u00f3n Norte\",\"datePublished\":\"2026-05-13T12:56:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/05\\\/13\\\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\\\/\"},\"wordCount\":143,\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/05\\\/13\\\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/pelota-kagiva-campo-oficial-1.jpg\",\"keywords\":[\"9 de julio Chacabuco\",\"club mercedes\",\"sub 13\",\"Sub 15\",\"Sub 17\",\"Torneo Federaci\u00f3n Norte\"],\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/05\\\/13\\\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/05\\\/13\\\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\\\/\",\"name\":\"Club Mercedes comenz\u00f3 su participaci\u00f3n en el Federaci\u00f3n Norte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/05\\\/13\\\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/05\\\/13\\\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/pelota-kagiva-campo-oficial-1.jpg\",\"datePublished\":\"2026-05-13T12:56:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/05\\\/13\\\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/05\\\/13\\\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/05\\\/13\\\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/pelota-kagiva-campo-oficial-1.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/pelota-kagiva-campo-oficial-1.jpg\",\"width\":800,\"height\":454,\"caption\":\"xr:d:DAFA54pM6v8:531,j:34506467687,t:22090423\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2026\\\/05\\\/13\\\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Club Mercedes comenz\u00f3 su participaci\u00f3n en el Federaci\u00f3n Norte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"description\":\"Mercedes, Buenos Aires, Argentina\",\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"width\":512,\"height\":512,\"caption\":\"NOTICIASMERCEDINAS.COM\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticiasmercedinas\\\/\",\"https:\\\/\\\/x.com\\\/notmercedinas\",\"https:\\\/\\\/www.instagram.com\\\/noticiasmercedinas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/8f2f09d666ef40986eba4a5e6f2a06f9\",\"name\":\"Juan Dagnino NOTICIASMERCEDINAS.COM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc7059a769f5a3cae65fadb228a3e4accf3a64b4b2305020d0a27e6d5333c91b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc7059a769f5a3cae65fadb228a3e4accf3a64b4b2305020d0a27e6d5333c91b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc7059a769f5a3cae65fadb228a3e4accf3a64b4b2305020d0a27e6d5333c91b?s=96&d=mm&r=g\",\"caption\":\"Juan Dagnino NOTICIASMERCEDINAS.COM\"},\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/author\\\/juandagnino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Club Mercedes comenz\u00f3 su participaci\u00f3n en el Federaci\u00f3n Norte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasmercedinas.com\/site\/2026\/05\/13\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\/","og_locale":"es_ES","og_type":"article","og_title":"Club Mercedes comenz\u00f3 su participaci\u00f3n en el Federaci\u00f3n Norte","og_description":"\u25a0 Anoche en su predio tuvo la visita de 9 de Julio de Chacabuco. El local gan\u00f3 en las categor\u00edas Su 17 y Sub 15 quedando el resultado para la visita en Sub 13. La pr\u00f3xima semana se jugar\u00e1 la segunda fecha.","og_url":"https:\/\/noticiasmercedinas.com\/site\/2026\/05\/13\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\/","og_site_name":"NOTICIASMERCEDINAS.COM","article_publisher":"https:\/\/www.facebook.com\/noticiasmercedinas\/","article_published_time":"2026-05-13T12:56:43+00:00","og_image":[{"width":800,"height":454,"url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/05\/pelota-kagiva-campo-oficial-1.jpg","type":"image\/jpeg"}],"author":"Juan Dagnino NOTICIASMERCEDINAS.COM","twitter_card":"summary_large_image","twitter_creator":"@notmercedinas","twitter_site":"@notmercedinas","twitter_misc":{"Escrito por":"Juan Dagnino NOTICIASMERCEDINAS.COM","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasmercedinas.com\/site\/2026\/05\/13\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\/#article","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2026\/05\/13\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\/"},"author":{"name":"Juan Dagnino NOTICIASMERCEDINAS.COM","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/8f2f09d666ef40986eba4a5e6f2a06f9"},"headline":"Club Mercedes comenz\u00f3 su participaci\u00f3n en el Federaci\u00f3n Norte","datePublished":"2026-05-13T12:56:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2026\/05\/13\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\/"},"wordCount":143,"publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2026\/05\/13\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/05\/pelota-kagiva-campo-oficial-1.jpg","keywords":["9 de julio Chacabuco","club mercedes","sub 13","Sub 15","Sub 17","Torneo Federaci\u00f3n Norte"],"articleSection":["Deportes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasmercedinas.com\/site\/2026\/05\/13\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\/","url":"https:\/\/noticiasmercedinas.com\/site\/2026\/05\/13\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\/","name":"Club Mercedes comenz\u00f3 su participaci\u00f3n en el Federaci\u00f3n Norte","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2026\/05\/13\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\/#primaryimage"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2026\/05\/13\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/05\/pelota-kagiva-campo-oficial-1.jpg","datePublished":"2026-05-13T12:56:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2026\/05\/13\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasmercedinas.com\/site\/2026\/05\/13\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/2026\/05\/13\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\/#primaryimage","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/05\/pelota-kagiva-campo-oficial-1.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2026\/05\/pelota-kagiva-campo-oficial-1.jpg","width":800,"height":454,"caption":"xr:d:DAFA54pM6v8:531,j:34506467687,t:22090423"},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasmercedinas.com\/site\/2026\/05\/13\/club-mercedes-comenzo-su-participacion-en-el-federacion-norte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noticiasmercedinas.com\/site\/"},{"@type":"ListItem","position":2,"name":"Club Mercedes comenz\u00f3 su participaci\u00f3n en el Federaci\u00f3n Norte"}]},{"@type":"WebSite","@id":"https:\/\/noticiasmercedinas.com\/site\/#website","url":"https:\/\/noticiasmercedinas.com\/site\/","name":"NOTICIASMERCEDINAS.COM","description":"Mercedes, Buenos Aires, Argentina","publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasmercedinas.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasmercedinas.com\/site\/#organization","name":"NOTICIASMERCEDINAS.COM","url":"https:\/\/noticiasmercedinas.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","width":512,"height":512,"caption":"NOTICIASMERCEDINAS.COM"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticiasmercedinas\/","https:\/\/x.com\/notmercedinas","https:\/\/www.instagram.com\/noticiasmercedinas\/"]},{"@type":"Person","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/8f2f09d666ef40986eba4a5e6f2a06f9","name":"Juan Dagnino NOTICIASMERCEDINAS.COM","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fc7059a769f5a3cae65fadb228a3e4accf3a64b4b2305020d0a27e6d5333c91b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fc7059a769f5a3cae65fadb228a3e4accf3a64b4b2305020d0a27e6d5333c91b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fc7059a769f5a3cae65fadb228a3e4accf3a64b4b2305020d0a27e6d5333c91b?s=96&d=mm&r=g","caption":"Juan Dagnino NOTICIASMERCEDINAS.COM"},"url":"https:\/\/noticiasmercedinas.com\/site\/author\/juandagnino\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/186359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/comments?post=186359"}],"version-history":[{"count":1,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/186359\/revisions"}],"predecessor-version":[{"id":186361,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/186359\/revisions\/186361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media\/186360"}],"wp:attachment":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media?parent=186359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/categories?post=186359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/tags?post=186359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}