{"id":31216,"date":"2019-10-18T09:52:31","date_gmt":"2019-10-18T12:52:31","guid":{"rendered":"https:\/\/noticiasmercedinas.com\/site\/?p=31216"},"modified":"2019-10-18T09:52:31","modified_gmt":"2019-10-18T12:52:31","slug":"con-el-oido-atento-en-la-palabra","status":"publish","type":"post","link":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/18\/con-el-oido-atento-en-la-palabra\/","title":{"rendered":"Con el o\u00eddo atento en la Palabra"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-31217\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/c6326489-126d-4891-8ac6-170f04fe644f-1024x576.jpg\" alt=\"\" width=\"640\" height=\"360\" srcset=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/c6326489-126d-4891-8ac6-170f04fe644f.jpg 1024w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/c6326489-126d-4891-8ac6-170f04fe644f-300x169.jpg 300w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/c6326489-126d-4891-8ac6-170f04fe644f-768x432.jpg 768w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/c6326489-126d-4891-8ac6-170f04fe644f-1022x576.jpg 1022w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/c6326489-126d-4891-8ac6-170f04fe644f-640x360.jpg 640w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/c6326489-126d-4891-8ac6-170f04fe644f-681x383.jpg 681w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Hoy es San Lucas y comenzamos saludando a quienes llevan el nombre de este Santo al que se le atribuye el tercero de los Evangelios.<\/p>\n<p>Cuenta la tradici\u00f3n que era m\u00e9dico, compa\u00f1ero de viaje de San Pablo, y que es quien describe la amabilidad de Cristo.<\/p>\n<p>Su Evangelio demuestra una estima particular por las mujeres y aporta datos espec\u00edficos sobre Mar\u00eda. Describe situaciones de mucha misericordia de Jes\u00fas a los enfermos, los peque\u00f1os y los pecadores.<\/p>\n<p>Se le llama tambi\u00e9n \u201cEvangelio de la oraci\u00f3n\u201d, porque es el que m\u00e1s describe los momentos trascendentales de Jes\u00fas en esta actitud. Su palabra insiste en el amor misericordioso de Dios, y es el Evangelio que nos habla de la infancia de Jes\u00fas, lo que ha inspirado grandes obras de arte.<\/p>\n<p>El Evangelio que se nos invita a reflexionar es el de <a href=\"http:\/\/evangeli.net\/evangelio\/dia\/2019-10-18\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #000080;\"><strong>Lucas cap\u00edtulo 10 vers\u00edculos 1 al 9<\/strong><\/span><\/a>, al que ya hemos hecho referencia cuando Jes\u00fas env\u00eda a predicar a otros 72 que dec\u00edamos que eran laicos. Pero hoy es aplicable tambi\u00e9n a Lucas, ya que este amigo de Pablo est\u00e1 entre los ap\u00f3stoles y es enviado a predicar y a dejarnos su Evangelio.<\/p>\n<p>Quiera el Se\u00f1or que nos habla por medio de ese Evangelio, de esta Palabra, hablarnos a nuestro coraz\u00f3n y que tambi\u00e9n nosotros seamos hombres de oraci\u00f3n, como es Jes\u00fas en relaci\u00f3n al Padre, en momentos trascendentales de la vida.<\/p>\n<p>Y tambi\u00e9n hoy tenemos la memoria de Nuestra Se\u00f1ora de Schoenstatt. Saludamos a todos los miembros de este movimiento apost\u00f3lico, y que le pidan de modo particular a la madre admirable que nos ense\u00f1e a todos a poner el o\u00eddo atento en el Evangelio de Lucas.<\/p>\n<p>Que la Sant\u00edsima Virgen nos acompa\u00f1e en esto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy es San Lucas y comenzamos saludando a quienes llevan el nombre de este Santo al que se le atribuye el tercero de los Evangelios. Cuenta la tradici\u00f3n que era m\u00e9dico, compa\u00f1ero de viaje de San Pablo, y que es quien describe la amabilidad de Cristo. Su Evangelio demuestra una estima particular por las mujeres [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":31217,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3876],"tags":[3879],"class_list":["post-31216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-semillas-de-vida","tag-semillas-de-vida"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Con el o\u00eddo atento en la Palabra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/18\/con-el-oido-atento-en-la-palabra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Con el o\u00eddo atento en la Palabra\" \/>\n<meta property=\"og:description\" content=\"Hoy es San Lucas y comenzamos saludando a quienes llevan el nombre de este Santo al que se le atribuye el tercero de los Evangelios. Cuenta la tradici\u00f3n que era m\u00e9dico, compa\u00f1ero de viaje de San Pablo, y que es quien describe la amabilidad de Cristo. Su Evangelio demuestra una estima particular por las mujeres [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/18\/con-el-oido-atento-en-la-palabra\/\" \/>\n<meta property=\"og:site_name\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticiasmercedinas\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-18T12:52:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/c6326489-126d-4891-8ac6-170f04fe644f.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"P. H\u00e9ctor Joaqu\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:site\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"P. H\u00e9ctor Joaqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/18\\\/con-el-oido-atento-en-la-palabra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/18\\\/con-el-oido-atento-en-la-palabra\\\/\"},\"author\":{\"name\":\"P. H\u00e9ctor Joaqu\u00edn\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/fa7a2dad804ceee0906a2c148245b4c4\"},\"headline\":\"Con el o\u00eddo atento en la Palabra\",\"datePublished\":\"2019-10-18T12:52:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/18\\\/con-el-oido-atento-en-la-palabra\\\/\"},\"wordCount\":320,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/18\\\/con-el-oido-atento-en-la-palabra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/c6326489-126d-4891-8ac6-170f04fe644f.jpg\",\"keywords\":[\"semillas de vida\"],\"articleSection\":[\"Semillas de vida\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/18\\\/con-el-oido-atento-en-la-palabra\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/18\\\/con-el-oido-atento-en-la-palabra\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/18\\\/con-el-oido-atento-en-la-palabra\\\/\",\"name\":\"Con el o\u00eddo atento en la Palabra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/18\\\/con-el-oido-atento-en-la-palabra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/18\\\/con-el-oido-atento-en-la-palabra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/c6326489-126d-4891-8ac6-170f04fe644f.jpg\",\"datePublished\":\"2019-10-18T12:52:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/18\\\/con-el-oido-atento-en-la-palabra\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/18\\\/con-el-oido-atento-en-la-palabra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/18\\\/con-el-oido-atento-en-la-palabra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/c6326489-126d-4891-8ac6-170f04fe644f.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/c6326489-126d-4891-8ac6-170f04fe644f.jpg\",\"width\":1024,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/18\\\/con-el-oido-atento-en-la-palabra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Con el o\u00eddo atento en la Palabra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"description\":\"Mercedes, Buenos Aires, Argentina\",\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"width\":512,\"height\":512,\"caption\":\"NOTICIASMERCEDINAS.COM\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticiasmercedinas\\\/\",\"https:\\\/\\\/x.com\\\/notmercedinas\",\"https:\\\/\\\/www.instagram.com\\\/noticiasmercedinas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/fa7a2dad804ceee0906a2c148245b4c4\",\"name\":\"P. H\u00e9ctor Joaqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g\",\"caption\":\"P. H\u00e9ctor Joaqu\u00edn\"},\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/author\\\/p-carlos-joaquin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Con el o\u00eddo atento en la Palabra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/18\/con-el-oido-atento-en-la-palabra\/","og_locale":"es_ES","og_type":"article","og_title":"Con el o\u00eddo atento en la Palabra","og_description":"Hoy es San Lucas y comenzamos saludando a quienes llevan el nombre de este Santo al que se le atribuye el tercero de los Evangelios. Cuenta la tradici\u00f3n que era m\u00e9dico, compa\u00f1ero de viaje de San Pablo, y que es quien describe la amabilidad de Cristo. Su Evangelio demuestra una estima particular por las mujeres [&hellip;]","og_url":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/18\/con-el-oido-atento-en-la-palabra\/","og_site_name":"NOTICIASMERCEDINAS.COM","article_publisher":"https:\/\/www.facebook.com\/noticiasmercedinas\/","article_published_time":"2019-10-18T12:52:31+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/c6326489-126d-4891-8ac6-170f04fe644f.jpg","type":"image\/jpeg"}],"author":"P. H\u00e9ctor Joaqu\u00edn","twitter_card":"summary_large_image","twitter_creator":"@notmercedinas","twitter_site":"@notmercedinas","twitter_misc":{"Escrito por":"P. H\u00e9ctor Joaqu\u00edn","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/18\/con-el-oido-atento-en-la-palabra\/#article","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/18\/con-el-oido-atento-en-la-palabra\/"},"author":{"name":"P. H\u00e9ctor Joaqu\u00edn","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/fa7a2dad804ceee0906a2c148245b4c4"},"headline":"Con el o\u00eddo atento en la Palabra","datePublished":"2019-10-18T12:52:31+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/18\/con-el-oido-atento-en-la-palabra\/"},"wordCount":320,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/18\/con-el-oido-atento-en-la-palabra\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/c6326489-126d-4891-8ac6-170f04fe644f.jpg","keywords":["semillas de vida"],"articleSection":["Semillas de vida"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasmercedinas.com\/site\/2019\/10\/18\/con-el-oido-atento-en-la-palabra\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/18\/con-el-oido-atento-en-la-palabra\/","url":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/18\/con-el-oido-atento-en-la-palabra\/","name":"Con el o\u00eddo atento en la Palabra","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/18\/con-el-oido-atento-en-la-palabra\/#primaryimage"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/18\/con-el-oido-atento-en-la-palabra\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/c6326489-126d-4891-8ac6-170f04fe644f.jpg","datePublished":"2019-10-18T12:52:31+00:00","breadcrumb":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/18\/con-el-oido-atento-en-la-palabra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasmercedinas.com\/site\/2019\/10\/18\/con-el-oido-atento-en-la-palabra\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/18\/con-el-oido-atento-en-la-palabra\/#primaryimage","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/c6326489-126d-4891-8ac6-170f04fe644f.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/c6326489-126d-4891-8ac6-170f04fe644f.jpg","width":1024,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/18\/con-el-oido-atento-en-la-palabra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noticiasmercedinas.com\/site\/"},{"@type":"ListItem","position":2,"name":"Con el o\u00eddo atento en la Palabra"}]},{"@type":"WebSite","@id":"https:\/\/noticiasmercedinas.com\/site\/#website","url":"https:\/\/noticiasmercedinas.com\/site\/","name":"NOTICIASMERCEDINAS.COM","description":"Mercedes, Buenos Aires, Argentina","publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasmercedinas.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasmercedinas.com\/site\/#organization","name":"NOTICIASMERCEDINAS.COM","url":"https:\/\/noticiasmercedinas.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","width":512,"height":512,"caption":"NOTICIASMERCEDINAS.COM"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticiasmercedinas\/","https:\/\/x.com\/notmercedinas","https:\/\/www.instagram.com\/noticiasmercedinas\/"]},{"@type":"Person","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/fa7a2dad804ceee0906a2c148245b4c4","name":"P. H\u00e9ctor Joaqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g","caption":"P. H\u00e9ctor Joaqu\u00edn"},"url":"https:\/\/noticiasmercedinas.com\/site\/author\/p-carlos-joaquin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/31216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/comments?post=31216"}],"version-history":[{"count":1,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/31216\/revisions"}],"predecessor-version":[{"id":31218,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/31216\/revisions\/31218"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media\/31217"}],"wp:attachment":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media?parent=31216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/categories?post=31216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/tags?post=31216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}