{"id":31839,"date":"2019-10-25T08:48:44","date_gmt":"2019-10-25T11:48:44","guid":{"rendered":"https:\/\/noticiasmercedinas.com\/site\/?p=31839"},"modified":"2019-10-25T08:48:44","modified_gmt":"2019-10-25T11:48:44","slug":"estar-atentos-a-los-signos-de-los-tiempos","status":"publish","type":"post","link":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/25\/estar-atentos-a-los-signos-de-los-tiempos\/","title":{"rendered":"Estar atentos a los signos de los tiempos"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-31840\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/world-press-photo-26-fevrier-2013-djibouti-des-migrants.jpg\" alt=\"\" width=\"730\" height=\"487\" srcset=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/world-press-photo-26-fevrier-2013-djibouti-des-migrants.jpg 730w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/world-press-photo-26-fevrier-2013-djibouti-des-migrants-300x200.jpg 300w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/world-press-photo-26-fevrier-2013-djibouti-des-migrants-640x427.jpg 640w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/world-press-photo-26-fevrier-2013-djibouti-des-migrants-681x454.jpg 681w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/p>\n<p>Estamos acostumbrados a o\u00edr hablar de \u201csignos\u201d. Los del zod\u00edaco, las se\u00f1ales de una serie de situaciones, de cosas, de indicaciones. Y Jes\u00fas comienza el Evangelio de hoy, que continuamos con <a href=\"http:\/\/evangeli.net\/evangelio\/dia\/2019-10-25\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #000080;\"><strong>Lucas cap\u00edtulo 12 vers\u00edculos 54 al 59<\/strong><\/span><\/a>, habl\u00e1ndonos <em>ustedes que saben si se levanta una nube de tal lugar acontece cual cosa<\/em>. Como decimos en el campo, <em>viento del este, lluvia como peste.<\/em><\/p>\n<p>Alguno dec\u00eda en alg\u00fan pueblo, <em>si cuando corre un poquito de viento se siente el ruido del tren es porque va a llover<\/em>. Eso sirve para ese pueblo solamente, pero somos dados a interpretar esos signos que nos da la naturaleza.<\/p>\n<p>El Se\u00f1or nos invita y nos dice <em>no sean insensatos, si saben discernir eso como es que no saben discernir el tiempo presente<\/em>. El Se\u00f1or nos habla en diversas situaciones, con signos, de all\u00ed la importancia \u2013como dec\u00eda el obispo Angelelli&#8211; de estar con un o\u00eddo atento en el Evangelio y un o\u00eddo atento en el pueblo.<\/p>\n<p>Los signos van aconteciendo en nuestro diario vivir y all\u00ed tenemos que escuchar lo que Dios quiere decirnos.<\/p>\n<p>La historia de la salvaci\u00f3n no es un libro muerto sino que es algo vital y se entreteje con nuestra propia vida y hace que seamos protagonistas de la trama.<\/p>\n<p>Por eso es bueno saber discernir lo bueno de lo malo, el buen camino del camino errado, y con mucha atenci\u00f3n para no caer en las trampas del demonio que es padre de la mentira y muchas veces quiere embrollarnos.<\/p>\n<p>Qu\u00e9 bueno es pedir a Dios Esp\u00edritu Santo el don de ciencia y de consejo, para en todo momento saber discernir qu\u00e9 nos quiere decir el Se\u00f1or con los acontecimientos de nuestra familia, en nuestra vida nacional, como pueblo, esos son los signos de los tiempos. Estemos atentos para responder adecuadamente.<\/p>\n<p>Que la Virgen Sant\u00edsima de Lujan nos acompa\u00f1e y bendiga.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estamos acostumbrados a o\u00edr hablar de \u201csignos\u201d. Los del zod\u00edaco, las se\u00f1ales de una serie de situaciones, de cosas, de indicaciones. Y Jes\u00fas comienza el Evangelio de hoy, que continuamos con Lucas cap\u00edtulo 12 vers\u00edculos 54 al 59, habl\u00e1ndonos ustedes que saben si se levanta una nube de tal lugar acontece cual cosa. Como decimos [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":31840,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3876],"tags":[3879],"class_list":["post-31839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-semillas-de-vida","tag-semillas-de-vida"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estar atentos a los signos de los tiempos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/25\/estar-atentos-a-los-signos-de-los-tiempos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estar atentos a los signos de los tiempos\" \/>\n<meta property=\"og:description\" content=\"Estamos acostumbrados a o\u00edr hablar de \u201csignos\u201d. Los del zod\u00edaco, las se\u00f1ales de una serie de situaciones, de cosas, de indicaciones. Y Jes\u00fas comienza el Evangelio de hoy, que continuamos con Lucas cap\u00edtulo 12 vers\u00edculos 54 al 59, habl\u00e1ndonos ustedes que saben si se levanta una nube de tal lugar acontece cual cosa. Como decimos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/25\/estar-atentos-a-los-signos-de-los-tiempos\/\" \/>\n<meta property=\"og:site_name\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticiasmercedinas\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-25T11:48:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/world-press-photo-26-fevrier-2013-djibouti-des-migrants.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"730\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"P. H\u00e9ctor Joaqu\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:site\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"P. H\u00e9ctor Joaqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/25\\\/estar-atentos-a-los-signos-de-los-tiempos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/25\\\/estar-atentos-a-los-signos-de-los-tiempos\\\/\"},\"author\":{\"name\":\"P. H\u00e9ctor Joaqu\u00edn\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/fa7a2dad804ceee0906a2c148245b4c4\"},\"headline\":\"Estar atentos a los signos de los tiempos\",\"datePublished\":\"2019-10-25T11:48:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/25\\\/estar-atentos-a-los-signos-de-los-tiempos\\\/\"},\"wordCount\":336,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/25\\\/estar-atentos-a-los-signos-de-los-tiempos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/world-press-photo-26-fevrier-2013-djibouti-des-migrants.jpg\",\"keywords\":[\"semillas de vida\"],\"articleSection\":[\"Semillas de vida\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/25\\\/estar-atentos-a-los-signos-de-los-tiempos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/25\\\/estar-atentos-a-los-signos-de-los-tiempos\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/25\\\/estar-atentos-a-los-signos-de-los-tiempos\\\/\",\"name\":\"Estar atentos a los signos de los tiempos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/25\\\/estar-atentos-a-los-signos-de-los-tiempos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/25\\\/estar-atentos-a-los-signos-de-los-tiempos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/world-press-photo-26-fevrier-2013-djibouti-des-migrants.jpg\",\"datePublished\":\"2019-10-25T11:48:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/25\\\/estar-atentos-a-los-signos-de-los-tiempos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/25\\\/estar-atentos-a-los-signos-de-los-tiempos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/25\\\/estar-atentos-a-los-signos-de-los-tiempos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/world-press-photo-26-fevrier-2013-djibouti-des-migrants.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/world-press-photo-26-fevrier-2013-djibouti-des-migrants.jpg\",\"width\":730,\"height\":487},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/10\\\/25\\\/estar-atentos-a-los-signos-de-los-tiempos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estar atentos a los signos de los tiempos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"description\":\"Mercedes, Buenos Aires, Argentina\",\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"width\":512,\"height\":512,\"caption\":\"NOTICIASMERCEDINAS.COM\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticiasmercedinas\\\/\",\"https:\\\/\\\/x.com\\\/notmercedinas\",\"https:\\\/\\\/www.instagram.com\\\/noticiasmercedinas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/fa7a2dad804ceee0906a2c148245b4c4\",\"name\":\"P. H\u00e9ctor Joaqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g\",\"caption\":\"P. H\u00e9ctor Joaqu\u00edn\"},\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/author\\\/p-carlos-joaquin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estar atentos a los signos de los tiempos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/25\/estar-atentos-a-los-signos-de-los-tiempos\/","og_locale":"es_ES","og_type":"article","og_title":"Estar atentos a los signos de los tiempos","og_description":"Estamos acostumbrados a o\u00edr hablar de \u201csignos\u201d. Los del zod\u00edaco, las se\u00f1ales de una serie de situaciones, de cosas, de indicaciones. Y Jes\u00fas comienza el Evangelio de hoy, que continuamos con Lucas cap\u00edtulo 12 vers\u00edculos 54 al 59, habl\u00e1ndonos ustedes que saben si se levanta una nube de tal lugar acontece cual cosa. Como decimos [&hellip;]","og_url":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/25\/estar-atentos-a-los-signos-de-los-tiempos\/","og_site_name":"NOTICIASMERCEDINAS.COM","article_publisher":"https:\/\/www.facebook.com\/noticiasmercedinas\/","article_published_time":"2019-10-25T11:48:44+00:00","og_image":[{"width":730,"height":487,"url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/world-press-photo-26-fevrier-2013-djibouti-des-migrants.jpg","type":"image\/jpeg"}],"author":"P. H\u00e9ctor Joaqu\u00edn","twitter_card":"summary_large_image","twitter_creator":"@notmercedinas","twitter_site":"@notmercedinas","twitter_misc":{"Escrito por":"P. H\u00e9ctor Joaqu\u00edn","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/25\/estar-atentos-a-los-signos-de-los-tiempos\/#article","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/25\/estar-atentos-a-los-signos-de-los-tiempos\/"},"author":{"name":"P. H\u00e9ctor Joaqu\u00edn","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/fa7a2dad804ceee0906a2c148245b4c4"},"headline":"Estar atentos a los signos de los tiempos","datePublished":"2019-10-25T11:48:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/25\/estar-atentos-a-los-signos-de-los-tiempos\/"},"wordCount":336,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/25\/estar-atentos-a-los-signos-de-los-tiempos\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/world-press-photo-26-fevrier-2013-djibouti-des-migrants.jpg","keywords":["semillas de vida"],"articleSection":["Semillas de vida"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasmercedinas.com\/site\/2019\/10\/25\/estar-atentos-a-los-signos-de-los-tiempos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/25\/estar-atentos-a-los-signos-de-los-tiempos\/","url":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/25\/estar-atentos-a-los-signos-de-los-tiempos\/","name":"Estar atentos a los signos de los tiempos","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/25\/estar-atentos-a-los-signos-de-los-tiempos\/#primaryimage"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/25\/estar-atentos-a-los-signos-de-los-tiempos\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/world-press-photo-26-fevrier-2013-djibouti-des-migrants.jpg","datePublished":"2019-10-25T11:48:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/25\/estar-atentos-a-los-signos-de-los-tiempos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasmercedinas.com\/site\/2019\/10\/25\/estar-atentos-a-los-signos-de-los-tiempos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/25\/estar-atentos-a-los-signos-de-los-tiempos\/#primaryimage","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/world-press-photo-26-fevrier-2013-djibouti-des-migrants.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/world-press-photo-26-fevrier-2013-djibouti-des-migrants.jpg","width":730,"height":487},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/10\/25\/estar-atentos-a-los-signos-de-los-tiempos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noticiasmercedinas.com\/site\/"},{"@type":"ListItem","position":2,"name":"Estar atentos a los signos de los tiempos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasmercedinas.com\/site\/#website","url":"https:\/\/noticiasmercedinas.com\/site\/","name":"NOTICIASMERCEDINAS.COM","description":"Mercedes, Buenos Aires, Argentina","publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasmercedinas.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasmercedinas.com\/site\/#organization","name":"NOTICIASMERCEDINAS.COM","url":"https:\/\/noticiasmercedinas.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","width":512,"height":512,"caption":"NOTICIASMERCEDINAS.COM"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticiasmercedinas\/","https:\/\/x.com\/notmercedinas","https:\/\/www.instagram.com\/noticiasmercedinas\/"]},{"@type":"Person","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/fa7a2dad804ceee0906a2c148245b4c4","name":"P. H\u00e9ctor Joaqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g","caption":"P. H\u00e9ctor Joaqu\u00edn"},"url":"https:\/\/noticiasmercedinas.com\/site\/author\/p-carlos-joaquin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/31839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/comments?post=31839"}],"version-history":[{"count":1,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/31839\/revisions"}],"predecessor-version":[{"id":31841,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/31839\/revisions\/31841"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media\/31840"}],"wp:attachment":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media?parent=31839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/categories?post=31839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/tags?post=31839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}