{"id":34758,"date":"2019-11-28T08:43:07","date_gmt":"2019-11-28T11:43:07","guid":{"rendered":"https:\/\/noticiasmercedinas.com\/site\/?p=34758"},"modified":"2019-11-28T08:43:07","modified_gmt":"2019-11-28T11:43:07","slug":"en-momentos-de-penuria-levantar-la-cabeza","status":"publish","type":"post","link":"https:\/\/noticiasmercedinas.com\/site\/2019\/11\/28\/en-momentos-de-penuria-levantar-la-cabeza\/","title":{"rendered":"En momentos de penuria, levantar la cabeza"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-34759\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/11\/liberacin-2-1024x640.jpg\" alt=\"\" width=\"640\" height=\"400\" srcset=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/11\/liberacin-2-1024x640.jpg 1024w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/11\/liberacin-2-300x188.jpg 300w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/11\/liberacin-2-768x480.jpg 768w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/11\/liberacin-2-640x400.jpg 640w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/11\/liberacin-2-681x426.jpg 681w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/11\/liberacin-2.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Hemos dicho que la \u00faltima semana del tiempo ordinario &#8211;despu\u00e9s de domingo pasado que hemos celebrado a Cristo Rey, y hoy jueves que estamos cercanos al domingo que daremos comienzo al Adviento&#8211;, en esta se mantiene el talante de la expectativa.<\/p>\n<p>La Iglesia nos invita a reflexionar el <a href=\"http:\/\/evangeli.net\/evangelio\/dia\/2019-11-28\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #000080;\"><strong>Evangelio de Lucas cap\u00edtulo 21 vers\u00edculos 20 al 28<\/strong><\/span><\/a> donde Jes\u00fas nos describe una serie de signos que se van a dar frente a la presidencia del Reino al final de la historia. Y es precisamente cuando Jes\u00fas dice \u201ctengan \u00e1nimo, levanten la cabeza porque est\u00e1 pronta la liberaci\u00f3n\u201d.<\/p>\n<p>En diversos momentos de nuestras vidas desfallecen nuestras fuerzas y nuestro \u00e1nimo, nuestra alma est\u00e1 como alica\u00edda, estamos desmotivados, y la invitaci\u00f3n que nos hace Jes\u00fas es ser persistentes en los momentos de penuria, levantar la cabeza, porque est\u00e1 cercana la liberaci\u00f3n.<\/p>\n<p>Siempre debemos contextualizar los textos que est\u00e1n escritos en plena \u00e9poca de persecuci\u00f3n a los cristianos, y hoy por hoy se persiguen las ideas o modelos de pensar del cristiano, que es burlado o vilipendiado por sus modos de pensar, ya que la civilizaci\u00f3n no es cristiana en sus criterios y es dif\u00edcil mantener nuestra postura de cristianos cat\u00f3licos convencidos y practicantes en los medios que nos movemos.<\/p>\n<p>Y Jes\u00fas nos invita a tener \u00e1nimo, porque est\u00e1 pronta la liberaci\u00f3n, que no es otra cosa que la presencia de Jes\u00fas en medio nuestro.<\/p>\n<p>Quiera la Virgen Sant\u00edsima animarnos a que en medio de nuestras dificultades, cuando nos cuesta ser transparencia de Jes\u00fas, tengamos el coraz\u00f3n en alto.<\/p>\n<p>Que Ella nos acompa\u00f1e, proteja y bendiga.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hemos dicho que la \u00faltima semana del tiempo ordinario &#8211;despu\u00e9s de domingo pasado que hemos celebrado a Cristo Rey, y hoy jueves que estamos cercanos al domingo que daremos comienzo al Adviento&#8211;, en esta se mantiene el talante de la expectativa. La Iglesia nos invita a reflexionar el Evangelio de Lucas cap\u00edtulo 21 vers\u00edculos 20 [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":34759,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3876],"tags":[3879],"class_list":["post-34758","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-semillas-de-vida","tag-semillas-de-vida"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En momentos de penuria, levantar la cabeza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasmercedinas.com\/site\/2019\/11\/28\/en-momentos-de-penuria-levantar-la-cabeza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En momentos de penuria, levantar la cabeza\" \/>\n<meta property=\"og:description\" content=\"Hemos dicho que la \u00faltima semana del tiempo ordinario &#8211;despu\u00e9s de domingo pasado que hemos celebrado a Cristo Rey, y hoy jueves que estamos cercanos al domingo que daremos comienzo al Adviento&#8211;, en esta se mantiene el talante de la expectativa. La Iglesia nos invita a reflexionar el Evangelio de Lucas cap\u00edtulo 21 vers\u00edculos 20 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasmercedinas.com\/site\/2019\/11\/28\/en-momentos-de-penuria-levantar-la-cabeza\/\" \/>\n<meta property=\"og:site_name\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticiasmercedinas\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-28T11:43:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/11\/liberacin-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"P. H\u00e9ctor Joaqu\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:site\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"P. H\u00e9ctor Joaqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/11\\\/28\\\/en-momentos-de-penuria-levantar-la-cabeza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/11\\\/28\\\/en-momentos-de-penuria-levantar-la-cabeza\\\/\"},\"author\":{\"name\":\"P. H\u00e9ctor Joaqu\u00edn\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/fa7a2dad804ceee0906a2c148245b4c4\"},\"headline\":\"En momentos de penuria, levantar la cabeza\",\"datePublished\":\"2019-11-28T11:43:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/11\\\/28\\\/en-momentos-de-penuria-levantar-la-cabeza\\\/\"},\"wordCount\":289,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/11\\\/28\\\/en-momentos-de-penuria-levantar-la-cabeza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/liberacin-2.jpg\",\"keywords\":[\"semillas de vida\"],\"articleSection\":[\"Semillas de vida\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/11\\\/28\\\/en-momentos-de-penuria-levantar-la-cabeza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/11\\\/28\\\/en-momentos-de-penuria-levantar-la-cabeza\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/11\\\/28\\\/en-momentos-de-penuria-levantar-la-cabeza\\\/\",\"name\":\"En momentos de penuria, levantar la cabeza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/11\\\/28\\\/en-momentos-de-penuria-levantar-la-cabeza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/11\\\/28\\\/en-momentos-de-penuria-levantar-la-cabeza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/liberacin-2.jpg\",\"datePublished\":\"2019-11-28T11:43:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/11\\\/28\\\/en-momentos-de-penuria-levantar-la-cabeza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/11\\\/28\\\/en-momentos-de-penuria-levantar-la-cabeza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/11\\\/28\\\/en-momentos-de-penuria-levantar-la-cabeza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/liberacin-2.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/liberacin-2.jpg\",\"width\":1080,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/11\\\/28\\\/en-momentos-de-penuria-levantar-la-cabeza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En momentos de penuria, levantar la cabeza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"description\":\"Mercedes, Buenos Aires, Argentina\",\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"width\":512,\"height\":512,\"caption\":\"NOTICIASMERCEDINAS.COM\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticiasmercedinas\\\/\",\"https:\\\/\\\/x.com\\\/notmercedinas\",\"https:\\\/\\\/www.instagram.com\\\/noticiasmercedinas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/fa7a2dad804ceee0906a2c148245b4c4\",\"name\":\"P. H\u00e9ctor Joaqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g\",\"caption\":\"P. H\u00e9ctor Joaqu\u00edn\"},\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/author\\\/p-carlos-joaquin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En momentos de penuria, levantar la cabeza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasmercedinas.com\/site\/2019\/11\/28\/en-momentos-de-penuria-levantar-la-cabeza\/","og_locale":"es_ES","og_type":"article","og_title":"En momentos de penuria, levantar la cabeza","og_description":"Hemos dicho que la \u00faltima semana del tiempo ordinario &#8211;despu\u00e9s de domingo pasado que hemos celebrado a Cristo Rey, y hoy jueves que estamos cercanos al domingo que daremos comienzo al Adviento&#8211;, en esta se mantiene el talante de la expectativa. La Iglesia nos invita a reflexionar el Evangelio de Lucas cap\u00edtulo 21 vers\u00edculos 20 [&hellip;]","og_url":"https:\/\/noticiasmercedinas.com\/site\/2019\/11\/28\/en-momentos-de-penuria-levantar-la-cabeza\/","og_site_name":"NOTICIASMERCEDINAS.COM","article_publisher":"https:\/\/www.facebook.com\/noticiasmercedinas\/","article_published_time":"2019-11-28T11:43:07+00:00","og_image":[{"width":1080,"height":675,"url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/11\/liberacin-2.jpg","type":"image\/jpeg"}],"author":"P. H\u00e9ctor Joaqu\u00edn","twitter_card":"summary_large_image","twitter_creator":"@notmercedinas","twitter_site":"@notmercedinas","twitter_misc":{"Escrito por":"P. H\u00e9ctor Joaqu\u00edn","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/11\/28\/en-momentos-de-penuria-levantar-la-cabeza\/#article","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/11\/28\/en-momentos-de-penuria-levantar-la-cabeza\/"},"author":{"name":"P. H\u00e9ctor Joaqu\u00edn","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/fa7a2dad804ceee0906a2c148245b4c4"},"headline":"En momentos de penuria, levantar la cabeza","datePublished":"2019-11-28T11:43:07+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/11\/28\/en-momentos-de-penuria-levantar-la-cabeza\/"},"wordCount":289,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/11\/28\/en-momentos-de-penuria-levantar-la-cabeza\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/11\/liberacin-2.jpg","keywords":["semillas de vida"],"articleSection":["Semillas de vida"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasmercedinas.com\/site\/2019\/11\/28\/en-momentos-de-penuria-levantar-la-cabeza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/11\/28\/en-momentos-de-penuria-levantar-la-cabeza\/","url":"https:\/\/noticiasmercedinas.com\/site\/2019\/11\/28\/en-momentos-de-penuria-levantar-la-cabeza\/","name":"En momentos de penuria, levantar la cabeza","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/11\/28\/en-momentos-de-penuria-levantar-la-cabeza\/#primaryimage"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/11\/28\/en-momentos-de-penuria-levantar-la-cabeza\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/11\/liberacin-2.jpg","datePublished":"2019-11-28T11:43:07+00:00","breadcrumb":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/11\/28\/en-momentos-de-penuria-levantar-la-cabeza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasmercedinas.com\/site\/2019\/11\/28\/en-momentos-de-penuria-levantar-la-cabeza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/11\/28\/en-momentos-de-penuria-levantar-la-cabeza\/#primaryimage","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/11\/liberacin-2.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/11\/liberacin-2.jpg","width":1080,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/11\/28\/en-momentos-de-penuria-levantar-la-cabeza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noticiasmercedinas.com\/site\/"},{"@type":"ListItem","position":2,"name":"En momentos de penuria, levantar la cabeza"}]},{"@type":"WebSite","@id":"https:\/\/noticiasmercedinas.com\/site\/#website","url":"https:\/\/noticiasmercedinas.com\/site\/","name":"NOTICIASMERCEDINAS.COM","description":"Mercedes, Buenos Aires, Argentina","publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasmercedinas.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasmercedinas.com\/site\/#organization","name":"NOTICIASMERCEDINAS.COM","url":"https:\/\/noticiasmercedinas.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","width":512,"height":512,"caption":"NOTICIASMERCEDINAS.COM"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticiasmercedinas\/","https:\/\/x.com\/notmercedinas","https:\/\/www.instagram.com\/noticiasmercedinas\/"]},{"@type":"Person","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/fa7a2dad804ceee0906a2c148245b4c4","name":"P. H\u00e9ctor Joaqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g","caption":"P. H\u00e9ctor Joaqu\u00edn"},"url":"https:\/\/noticiasmercedinas.com\/site\/author\/p-carlos-joaquin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/34758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/comments?post=34758"}],"version-history":[{"count":1,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/34758\/revisions"}],"predecessor-version":[{"id":34760,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/34758\/revisions\/34760"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media\/34759"}],"wp:attachment":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media?parent=34758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/categories?post=34758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/tags?post=34758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}