{"id":36359,"date":"2019-12-17T10:17:42","date_gmt":"2019-12-17T13:17:42","guid":{"rendered":"https:\/\/noticiasmercedinas.com\/site\/?p=36359"},"modified":"2019-12-17T10:17:42","modified_gmt":"2019-12-17T13:17:42","slug":"verdadero-hombre-y-rey","status":"publish","type":"post","link":"https:\/\/noticiasmercedinas.com\/site\/2019\/12\/17\/verdadero-hombre-y-rey\/","title":{"rendered":"Verdadero Hombre y Rey"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-36360\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/12\/fe59fc501fd2bfdb32860f614bef63f3.jpg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/12\/fe59fc501fd2bfdb32860f614bef63f3.jpg 960w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/12\/fe59fc501fd2bfdb32860f614bef63f3-300x225.jpg 300w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/12\/fe59fc501fd2bfdb32860f614bef63f3-768x576.jpg 768w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/12\/fe59fc501fd2bfdb32860f614bef63f3-80x60.jpg 80w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/12\/fe59fc501fd2bfdb32860f614bef63f3-160x120.jpg 160w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/12\/fe59fc501fd2bfdb32860f614bef63f3-100x75.jpg 100w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/12\/fe59fc501fd2bfdb32860f614bef63f3-200x150.jpg 200w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/12\/fe59fc501fd2bfdb32860f614bef63f3-180x135.jpg 180w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/12\/fe59fc501fd2bfdb32860f614bef63f3-360x270.jpg 360w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/12\/fe59fc501fd2bfdb32860f614bef63f3-238x178.jpg 238w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/12\/fe59fc501fd2bfdb32860f614bef63f3-476x356.jpg 476w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/12\/fe59fc501fd2bfdb32860f614bef63f3-640x480.jpg 640w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/12\/fe59fc501fd2bfdb32860f614bef63f3-681x511.jpg 681w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/p>\n<p>Hemos comenzado ayer la Novena de la Navidad y hoy martes 17 nos unimos al Papa Francisco que cumple a\u00f1os. Cumple 83 j\u00f3venes a\u00f1os al servicio de la Iglesia. Hace poco ha celebrado su cincuentenario como sacerdote. Nos unimos a \u00e9l y pedimos por sus intenciones.<\/p>\n<p>Se nos invita en esta semana a leer el <a href=\"http:\/\/evangeli.net\/evangelio\/dia\/2019-12-17\" target=\"_blank\" rel=\"noopener noreferrer\"><strong><span style=\"color: #000080;\">Evangelio de Mateo, cap\u00edtulo 1 vers\u00edculos 1 al 17<\/span><\/strong><\/a>, donde el evangelista Mateo se preocupa de mostrarnos la genealog\u00eda de Jes\u00fas, para mostrarnos que es un verdadero hombre y no solamente eso sino que desciende de un linaje real. Por eso es verdadero Hombre y verdadero Rey, y en unos d\u00edas vamos a ver que tambi\u00e9n es verdadero Dios.<\/p>\n<p>Pero hoy se nos invita a contemplar la humanidad de Jes\u00fas, ratificada porque es hijo de Mar\u00eda Sant\u00edsima, ser humano, virginalmente concebido, pero en compa\u00f1\u00eda de un var\u00f3n nace de una mujer. Y una mujer no puede sino engendrar un hombre. Concebido por el Esp\u00edritu Santo pero nace de una mujer, es el fruto bendito del vientre de Mar\u00eda que desde su seno es ungido por la realeza porque es Jos\u00e9 el compa\u00f1ero de Mar\u00eda, con quien no convive, no tiene relaci\u00f3n, es el casto Jos\u00e9 y es Mar\u00eda virgen. Y es Jos\u00e9 quien pone el pecho y lo presenta como su verdadero hijo y as\u00ed adquiere este linaje porque Jos\u00e9 es descendiente de la familia de David. Posteriormente lo conoceremos a Jes\u00fas como verdadero Rey y \u00e9l mismo dice \u201cMi Reino no es de este mundo\u201d.<\/p>\n<p>El Evangelio de hoy, de Mateo, nos invita a ver esta dimensi\u00f3n humana de Jes\u00fas y preparar tambi\u00e9n nuestro coraz\u00f3n humano con lo que tenemos de humano para recibirlo porque El viene.<\/p>\n<p>Que la Virgen de Luj\u00e1n nos ayude a preparar el lugar para este Hombre que nace.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hemos comenzado ayer la Novena de la Navidad y hoy martes 17 nos unimos al Papa Francisco que cumple a\u00f1os. Cumple 83 j\u00f3venes a\u00f1os al servicio de la Iglesia. Hace poco ha celebrado su cincuentenario como sacerdote. Nos unimos a \u00e9l y pedimos por sus intenciones. Se nos invita en esta semana a leer el [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":36360,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3876],"tags":[3879],"class_list":["post-36359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-semillas-de-vida","tag-semillas-de-vida"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verdadero Hombre y Rey<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasmercedinas.com\/site\/2019\/12\/17\/verdadero-hombre-y-rey\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verdadero Hombre y Rey\" \/>\n<meta property=\"og:description\" content=\"Hemos comenzado ayer la Novena de la Navidad y hoy martes 17 nos unimos al Papa Francisco que cumple a\u00f1os. Cumple 83 j\u00f3venes a\u00f1os al servicio de la Iglesia. Hace poco ha celebrado su cincuentenario como sacerdote. Nos unimos a \u00e9l y pedimos por sus intenciones. Se nos invita en esta semana a leer el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasmercedinas.com\/site\/2019\/12\/17\/verdadero-hombre-y-rey\/\" \/>\n<meta property=\"og:site_name\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticiasmercedinas\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-17T13:17:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/12\/fe59fc501fd2bfdb32860f614bef63f3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"P. H\u00e9ctor Joaqu\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:site\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"P. H\u00e9ctor Joaqu\u00edn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/12\\\/17\\\/verdadero-hombre-y-rey\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/12\\\/17\\\/verdadero-hombre-y-rey\\\/\"},\"author\":{\"name\":\"P. H\u00e9ctor Joaqu\u00edn\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/fa7a2dad804ceee0906a2c148245b4c4\"},\"headline\":\"Verdadero Hombre y Rey\",\"datePublished\":\"2019-12-17T13:17:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/12\\\/17\\\/verdadero-hombre-y-rey\\\/\"},\"wordCount\":324,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/12\\\/17\\\/verdadero-hombre-y-rey\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/fe59fc501fd2bfdb32860f614bef63f3.jpg\",\"keywords\":[\"semillas de vida\"],\"articleSection\":[\"Semillas de vida\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/12\\\/17\\\/verdadero-hombre-y-rey\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/12\\\/17\\\/verdadero-hombre-y-rey\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/12\\\/17\\\/verdadero-hombre-y-rey\\\/\",\"name\":\"Verdadero Hombre y Rey\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/12\\\/17\\\/verdadero-hombre-y-rey\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/12\\\/17\\\/verdadero-hombre-y-rey\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/fe59fc501fd2bfdb32860f614bef63f3.jpg\",\"datePublished\":\"2019-12-17T13:17:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/12\\\/17\\\/verdadero-hombre-y-rey\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/12\\\/17\\\/verdadero-hombre-y-rey\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/12\\\/17\\\/verdadero-hombre-y-rey\\\/#primaryimage\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/fe59fc501fd2bfdb32860f614bef63f3.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/fe59fc501fd2bfdb32860f614bef63f3.jpg\",\"width\":960,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2019\\\/12\\\/17\\\/verdadero-hombre-y-rey\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verdadero Hombre y Rey\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"description\":\"Mercedes, Buenos Aires, Argentina\",\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"width\":512,\"height\":512,\"caption\":\"NOTICIASMERCEDINAS.COM\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticiasmercedinas\\\/\",\"https:\\\/\\\/x.com\\\/notmercedinas\",\"https:\\\/\\\/www.instagram.com\\\/noticiasmercedinas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/fa7a2dad804ceee0906a2c148245b4c4\",\"name\":\"P. H\u00e9ctor Joaqu\u00edn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g\",\"caption\":\"P. H\u00e9ctor Joaqu\u00edn\"},\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/author\\\/p-carlos-joaquin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verdadero Hombre y Rey","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasmercedinas.com\/site\/2019\/12\/17\/verdadero-hombre-y-rey\/","og_locale":"es_ES","og_type":"article","og_title":"Verdadero Hombre y Rey","og_description":"Hemos comenzado ayer la Novena de la Navidad y hoy martes 17 nos unimos al Papa Francisco que cumple a\u00f1os. Cumple 83 j\u00f3venes a\u00f1os al servicio de la Iglesia. Hace poco ha celebrado su cincuentenario como sacerdote. Nos unimos a \u00e9l y pedimos por sus intenciones. Se nos invita en esta semana a leer el [&hellip;]","og_url":"https:\/\/noticiasmercedinas.com\/site\/2019\/12\/17\/verdadero-hombre-y-rey\/","og_site_name":"NOTICIASMERCEDINAS.COM","article_publisher":"https:\/\/www.facebook.com\/noticiasmercedinas\/","article_published_time":"2019-12-17T13:17:42+00:00","og_image":[{"width":960,"height":720,"url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/12\/fe59fc501fd2bfdb32860f614bef63f3.jpg","type":"image\/jpeg"}],"author":"P. H\u00e9ctor Joaqu\u00edn","twitter_card":"summary_large_image","twitter_creator":"@notmercedinas","twitter_site":"@notmercedinas","twitter_misc":{"Escrito por":"P. H\u00e9ctor Joaqu\u00edn","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/12\/17\/verdadero-hombre-y-rey\/#article","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/12\/17\/verdadero-hombre-y-rey\/"},"author":{"name":"P. H\u00e9ctor Joaqu\u00edn","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/fa7a2dad804ceee0906a2c148245b4c4"},"headline":"Verdadero Hombre y Rey","datePublished":"2019-12-17T13:17:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/12\/17\/verdadero-hombre-y-rey\/"},"wordCount":324,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/12\/17\/verdadero-hombre-y-rey\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/12\/fe59fc501fd2bfdb32860f614bef63f3.jpg","keywords":["semillas de vida"],"articleSection":["Semillas de vida"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasmercedinas.com\/site\/2019\/12\/17\/verdadero-hombre-y-rey\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/12\/17\/verdadero-hombre-y-rey\/","url":"https:\/\/noticiasmercedinas.com\/site\/2019\/12\/17\/verdadero-hombre-y-rey\/","name":"Verdadero Hombre y Rey","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/12\/17\/verdadero-hombre-y-rey\/#primaryimage"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/12\/17\/verdadero-hombre-y-rey\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/12\/fe59fc501fd2bfdb32860f614bef63f3.jpg","datePublished":"2019-12-17T13:17:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/12\/17\/verdadero-hombre-y-rey\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasmercedinas.com\/site\/2019\/12\/17\/verdadero-hombre-y-rey\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/12\/17\/verdadero-hombre-y-rey\/#primaryimage","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/12\/fe59fc501fd2bfdb32860f614bef63f3.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/12\/fe59fc501fd2bfdb32860f614bef63f3.jpg","width":960,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasmercedinas.com\/site\/2019\/12\/17\/verdadero-hombre-y-rey\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noticiasmercedinas.com\/site\/"},{"@type":"ListItem","position":2,"name":"Verdadero Hombre y Rey"}]},{"@type":"WebSite","@id":"https:\/\/noticiasmercedinas.com\/site\/#website","url":"https:\/\/noticiasmercedinas.com\/site\/","name":"NOTICIASMERCEDINAS.COM","description":"Mercedes, Buenos Aires, Argentina","publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasmercedinas.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasmercedinas.com\/site\/#organization","name":"NOTICIASMERCEDINAS.COM","url":"https:\/\/noticiasmercedinas.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","width":512,"height":512,"caption":"NOTICIASMERCEDINAS.COM"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticiasmercedinas\/","https:\/\/x.com\/notmercedinas","https:\/\/www.instagram.com\/noticiasmercedinas\/"]},{"@type":"Person","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/fa7a2dad804ceee0906a2c148245b4c4","name":"P. H\u00e9ctor Joaqu\u00edn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fc990d0c6aaa5e2392b464cdcac996d997f9584e171f3aa7796a8414f18ec701?s=96&d=mm&r=g","caption":"P. H\u00e9ctor Joaqu\u00edn"},"url":"https:\/\/noticiasmercedinas.com\/site\/author\/p-carlos-joaquin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/36359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/comments?post=36359"}],"version-history":[{"count":1,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/36359\/revisions"}],"predecessor-version":[{"id":36361,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/36359\/revisions\/36361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media\/36360"}],"wp:attachment":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media?parent=36359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/categories?post=36359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/tags?post=36359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}