{"id":7974,"date":"2018-11-29T17:11:00","date_gmt":"2018-11-29T20:11:00","guid":{"rendered":"https:\/\/noticiasmercedinas.com\/site\/?p=7974"},"modified":"2018-11-29T22:48:04","modified_gmt":"2018-11-30T01:48:04","slug":"mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha","status":"publish","type":"post","link":"https:\/\/noticiasmercedinas.com\/site\/2018\/11\/29\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\/","title":{"rendered":"Mercado Sustentable abre sus puertas este s\u00e1bado en La Trocha"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-7975\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2018\/11\/mercadosaludable.jpg\" alt=\"\" width=\"958\" height=\"960\" srcset=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2018\/11\/mercadosaludable.jpg 958w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2018\/11\/mercadosaludable-150x150.jpg 150w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2018\/11\/mercadosaludable-300x300.jpg 300w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2018\/11\/mercadosaludable-768x770.jpg 768w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2018\/11\/mercadosaludable-640x641.jpg 640w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2018\/11\/mercadosaludable-681x682.jpg 681w\" sizes=\"auto, (max-width: 958px) 100vw, 958px\" \/><\/p>\n<p style=\"font-weight: 400;\">Este 1 de diciembre abrir\u00e1 sus puertas el 1\u00b0 Mercado Sustentable en La Trocha. Su objetivo es que los productores locales puedan poner a la venta sus productos \u2013agroecol\u00f3gicos u org\u00e1nicos- sin mediadores, de la tierra a la mesa.<\/p>\n<p style=\"font-weight: 400;\">Toda la puesta en marcha es con materiales reciclados y ser\u00e1 desde las 10 horas la apertura del mismo y estar\u00e1 hasta las 15 horas.<\/p>\n<p style=\"font-weight: 400;\"><strong>Habr\u00e1 verduras de la huerta agroecol\u00f3gica, panificados y resposter\u00eda integral, dulces y conservas caseras, miel, queso, huevos de campo, jugos naturales, cerveza artesanal, vino patero, medicina y cosm\u00e9tica natural, patio gastron\u00f3mico saludable y mucho m\u00e1s.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Uno de los objetivos, adem\u00e1s, es que este nuevo espacio sirva de punto de reuni\u00f3n para todos aquellos que ya vienen desarrollando esta tem\u00e1tica, y el vecino de la ciudad encuentre y satisfaga, con precios m\u00e1s cuidados, a trav\u00e9s de una compra directa, sus necesidades alimenticias.<\/p>\n<p style=\"font-weight: 400;\">La idea del mismo es que sea un mercado que funcione un s\u00e1bado cada 15 d\u00edas -de 10:00 a 15:00 horas- que contenga alimentos agroecol\u00f3gicos u org\u00e1nicos para peque\u00f1os productores locales \u201cpara que la gente pueda comprarle al productor sin mediaciones y empezar a trabajar sobre el reciclado y lo sustentable en la ciudad\u201d seg\u00fan puntualiz\u00f3 Jorgelina Silva, de Desarrollo Social.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-7976\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2018\/11\/mercado-saludable-1.jpg\" alt=\"\" width=\"937\" height=\"626\" srcset=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2018\/11\/mercado-saludable-1.jpg 937w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2018\/11\/mercado-saludable-1-300x200.jpg 300w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2018\/11\/mercado-saludable-1-768x513.jpg 768w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2018\/11\/mercado-saludable-1-537x360.jpg 537w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2018\/11\/mercado-saludable-1-640x428.jpg 640w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2018\/11\/mercado-saludable-1-681x455.jpg 681w\" sizes=\"auto, (max-width: 937px) 100vw, 937px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este 1 de diciembre abrir\u00e1 sus puertas el 1\u00b0 Mercado Sustentable en La Trocha. Su objetivo es que los productores locales puedan poner a la venta sus productos \u2013agroecol\u00f3gicos u org\u00e1nicos- sin mediadores, de la tierra a la mesa. Toda la puesta en marcha es con materiales reciclados y ser\u00e1 desde las 10 horas la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7975,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[1123,2493,2500,2492,2490,2496,2497,2499,2142,2494,2491,2501,2495,2489,2498],"class_list":["post-7974","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad","tag-cerveza-artesanal","tag-conservas-caseras","tag-cosmetica-natural","tag-dulces","tag-huerta-agroecologica","tag-huevos-de-campo","tag-jugos-naturales","tag-medicina","tag-mercado-sustentable-la-trocha","tag-miel","tag-panificados-y-resposteria-integral","tag-patio-gastronomico-saludable","tag-queso","tag-verduras","tag-vino-patero"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mercado Sustentable abre sus puertas este s\u00e1bado en La Trocha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasmercedinas.com\/site\/2018\/11\/29\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercado Sustentable abre sus puertas este s\u00e1bado en La Trocha\" \/>\n<meta property=\"og:description\" content=\"Este 1 de diciembre abrir\u00e1 sus puertas el 1\u00b0 Mercado Sustentable en La Trocha. Su objetivo es que los productores locales puedan poner a la venta sus productos \u2013agroecol\u00f3gicos u org\u00e1nicos- sin mediadores, de la tierra a la mesa. Toda la puesta en marcha es con materiales reciclados y ser\u00e1 desde las 10 horas la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasmercedinas.com\/site\/2018\/11\/29\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\/\" \/>\n<meta property=\"og:site_name\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticiasmercedinas\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/cristian.falabella\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-29T20:11:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-30T01:48:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2018\/11\/mercadosaludable.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"958\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cristian Falabella NOTICIASMERCEDINAS.COM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/NOTMERCEDINAS\" \/>\n<meta name=\"twitter:site\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cristian Falabella NOTICIASMERCEDINAS.COM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2018\\\/11\\\/29\\\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2018\\\/11\\\/29\\\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\\\/\"},\"author\":{\"name\":\"Cristian Falabella NOTICIASMERCEDINAS.COM\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/d481a9696a5feaec13a60e2bbd991a6a\"},\"headline\":\"Mercado Sustentable abre sus puertas este s\u00e1bado en La Trocha\",\"datePublished\":\"2018-11-29T20:11:00+00:00\",\"dateModified\":\"2018-11-30T01:48:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2018\\\/11\\\/29\\\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\\\/\"},\"wordCount\":228,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2018\\\/11\\\/29\\\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/mercadosaludable.jpg\",\"keywords\":[\"cerveza artesanal\",\"conservas caseras\",\"cosm\u00e9tica natural\",\"dulces\",\"huerta agroecol\u00f3gica\",\"huevos de campo\",\"jugos naturales\",\"medicina\",\"mercado sustentable La Trocha\",\"miel\",\"panificados y resposter\u00eda integral\",\"patio gastron\u00f3mico saludable\",\"queso\",\"verduras\",\"vino patero\"],\"articleSection\":[\"Sociedad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2018\\\/11\\\/29\\\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2018\\\/11\\\/29\\\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2018\\\/11\\\/29\\\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\\\/\",\"name\":\"Mercado Sustentable abre sus puertas este s\u00e1bado en La Trocha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2018\\\/11\\\/29\\\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2018\\\/11\\\/29\\\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/mercadosaludable.jpg\",\"datePublished\":\"2018-11-29T20:11:00+00:00\",\"dateModified\":\"2018-11-30T01:48:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2018\\\/11\\\/29\\\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2018\\\/11\\\/29\\\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2018\\\/11\\\/29\\\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\\\/#primaryimage\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/mercadosaludable.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/mercadosaludable.jpg\",\"width\":958,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2018\\\/11\\\/29\\\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado Sustentable abre sus puertas este s\u00e1bado en La Trocha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"description\":\"Mercedes, Buenos Aires, Argentina\",\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"width\":512,\"height\":512,\"caption\":\"NOTICIASMERCEDINAS.COM\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticiasmercedinas\\\/\",\"https:\\\/\\\/x.com\\\/notmercedinas\",\"https:\\\/\\\/www.instagram.com\\\/noticiasmercedinas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/d481a9696a5feaec13a60e2bbd991a6a\",\"name\":\"Cristian Falabella NOTICIASMERCEDINAS.COM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0dbbfc45970cc46bcd0e57766228574ff3511d6eed045b182f536f0f478c1f06?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0dbbfc45970cc46bcd0e57766228574ff3511d6eed045b182f536f0f478c1f06?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0dbbfc45970cc46bcd0e57766228574ff3511d6eed045b182f536f0f478c1f06?s=96&d=mm&r=g\",\"caption\":\"Cristian Falabella NOTICIASMERCEDINAS.COM\"},\"description\":\"Periodista, editor de Noticias Mercedinas. Pas\u00f3 por varias redacciones y emprendimientos de prensa, en distintos formatos y \u00e9pocas. Se especializ\u00f3 --y sigue haci\u00e9ndolo-- en comunicaci\u00f3n en la web y en junio de 2006 fund\u00f3 este diario digital.\",\"sameAs\":[\"https:\\\/\\\/noticiasmercedinas.com\",\"https:\\\/\\\/www.facebook.com\\\/cristian.falabella\",\"https:\\\/\\\/www.instagram.com\\\/noticiasmercedinas\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/NOTMERCEDINAS\"],\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/author\\\/as000384\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mercado Sustentable abre sus puertas este s\u00e1bado en La Trocha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasmercedinas.com\/site\/2018\/11\/29\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\/","og_locale":"es_ES","og_type":"article","og_title":"Mercado Sustentable abre sus puertas este s\u00e1bado en La Trocha","og_description":"Este 1 de diciembre abrir\u00e1 sus puertas el 1\u00b0 Mercado Sustentable en La Trocha. Su objetivo es que los productores locales puedan poner a la venta sus productos \u2013agroecol\u00f3gicos u org\u00e1nicos- sin mediadores, de la tierra a la mesa. Toda la puesta en marcha es con materiales reciclados y ser\u00e1 desde las 10 horas la [&hellip;]","og_url":"https:\/\/noticiasmercedinas.com\/site\/2018\/11\/29\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\/","og_site_name":"NOTICIASMERCEDINAS.COM","article_publisher":"https:\/\/www.facebook.com\/noticiasmercedinas\/","article_author":"https:\/\/www.facebook.com\/cristian.falabella","article_published_time":"2018-11-29T20:11:00+00:00","article_modified_time":"2018-11-30T01:48:04+00:00","og_image":[{"width":958,"height":960,"url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2018\/11\/mercadosaludable.jpg","type":"image\/jpeg"}],"author":"Cristian Falabella NOTICIASMERCEDINAS.COM","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/NOTMERCEDINAS","twitter_site":"@notmercedinas","twitter_misc":{"Escrito por":"Cristian Falabella NOTICIASMERCEDINAS.COM","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasmercedinas.com\/site\/2018\/11\/29\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\/#article","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2018\/11\/29\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\/"},"author":{"name":"Cristian Falabella NOTICIASMERCEDINAS.COM","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/d481a9696a5feaec13a60e2bbd991a6a"},"headline":"Mercado Sustentable abre sus puertas este s\u00e1bado en La Trocha","datePublished":"2018-11-29T20:11:00+00:00","dateModified":"2018-11-30T01:48:04+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2018\/11\/29\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\/"},"wordCount":228,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2018\/11\/29\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2018\/11\/mercadosaludable.jpg","keywords":["cerveza artesanal","conservas caseras","cosm\u00e9tica natural","dulces","huerta agroecol\u00f3gica","huevos de campo","jugos naturales","medicina","mercado sustentable La Trocha","miel","panificados y resposter\u00eda integral","patio gastron\u00f3mico saludable","queso","verduras","vino patero"],"articleSection":["Sociedad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasmercedinas.com\/site\/2018\/11\/29\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasmercedinas.com\/site\/2018\/11\/29\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\/","url":"https:\/\/noticiasmercedinas.com\/site\/2018\/11\/29\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\/","name":"Mercado Sustentable abre sus puertas este s\u00e1bado en La Trocha","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2018\/11\/29\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\/#primaryimage"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2018\/11\/29\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2018\/11\/mercadosaludable.jpg","datePublished":"2018-11-29T20:11:00+00:00","dateModified":"2018-11-30T01:48:04+00:00","breadcrumb":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2018\/11\/29\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasmercedinas.com\/site\/2018\/11\/29\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/2018\/11\/29\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\/#primaryimage","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2018\/11\/mercadosaludable.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2018\/11\/mercadosaludable.jpg","width":958,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasmercedinas.com\/site\/2018\/11\/29\/mercado-sustentable-abre-sus-puerta-este-sabado-en-la-trocha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noticiasmercedinas.com\/site\/"},{"@type":"ListItem","position":2,"name":"Mercado Sustentable abre sus puertas este s\u00e1bado en La Trocha"}]},{"@type":"WebSite","@id":"https:\/\/noticiasmercedinas.com\/site\/#website","url":"https:\/\/noticiasmercedinas.com\/site\/","name":"NOTICIASMERCEDINAS.COM","description":"Mercedes, Buenos Aires, Argentina","publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasmercedinas.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasmercedinas.com\/site\/#organization","name":"NOTICIASMERCEDINAS.COM","url":"https:\/\/noticiasmercedinas.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","width":512,"height":512,"caption":"NOTICIASMERCEDINAS.COM"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticiasmercedinas\/","https:\/\/x.com\/notmercedinas","https:\/\/www.instagram.com\/noticiasmercedinas\/"]},{"@type":"Person","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/d481a9696a5feaec13a60e2bbd991a6a","name":"Cristian Falabella NOTICIASMERCEDINAS.COM","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0dbbfc45970cc46bcd0e57766228574ff3511d6eed045b182f536f0f478c1f06?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0dbbfc45970cc46bcd0e57766228574ff3511d6eed045b182f536f0f478c1f06?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0dbbfc45970cc46bcd0e57766228574ff3511d6eed045b182f536f0f478c1f06?s=96&d=mm&r=g","caption":"Cristian Falabella NOTICIASMERCEDINAS.COM"},"description":"Periodista, editor de Noticias Mercedinas. Pas\u00f3 por varias redacciones y emprendimientos de prensa, en distintos formatos y \u00e9pocas. Se especializ\u00f3 --y sigue haci\u00e9ndolo-- en comunicaci\u00f3n en la web y en junio de 2006 fund\u00f3 este diario digital.","sameAs":["https:\/\/noticiasmercedinas.com","https:\/\/www.facebook.com\/cristian.falabella","https:\/\/www.instagram.com\/noticiasmercedinas\/","https:\/\/x.com\/https:\/\/twitter.com\/NOTMERCEDINAS"],"url":"https:\/\/noticiasmercedinas.com\/site\/author\/as000384\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/7974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/comments?post=7974"}],"version-history":[{"count":4,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/7974\/revisions"}],"predecessor-version":[{"id":8015,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/7974\/revisions\/8015"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media\/7975"}],"wp:attachment":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media?parent=7974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/categories?post=7974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/tags?post=7974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}