{"id":89437,"date":"2022-04-28T17:53:52","date_gmt":"2022-04-28T20:53:52","guid":{"rendered":"https:\/\/noticiasmercedinas.com\/site\/?p=89437"},"modified":"2022-04-28T17:53:52","modified_gmt":"2022-04-28T20:53:52","slug":"destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias","status":"publish","type":"post","link":"https:\/\/noticiasmercedinas.com\/site\/2022\/04\/28\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\/","title":{"rendered":"Destacan importancia de misi\u00f3n a Israel para el desarrollo econ\u00f3mico y tecnol\u00f3gico de las provincias"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-89438\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1574-1.jpg\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1574-1.jpg 640w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1574-1-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Los gobernadores y gobernadoras que participaron de la misi\u00f3n a Israel encabezada por el ministro del Interior, Wado de Pedro, para interiorizarse sobre el manejo del agua, destacaron el trabajo en conjunto con los funcionarios del Gobierno nacional y tildaron a la experiencia como \u201cmuy importante para el desarrollo\u201d de las provincias.<\/p>\n<p>En ese marco, el gobernador de Catamarca, Ra\u00fal Jalil, destac\u00f3 que \u201cel camino de la paz y las relaciones es el \u00fanico camino que tenemos de abrirnos al mundo\u201d, y agradeci\u00f3 la oportunidad de haber formado parte de la comitiva que, desde 22 al 28 de abril, recorri\u00f3 plantas de desalinizaci\u00f3n, riego y medici\u00f3n inteligente en distintos puntos de Israel, y mantuvo encuentros con funcionarios israel\u00edes.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-89443\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1810.jpg\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1810.jpg 640w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1810-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>\u201cLa verdad es que me voy muy conforme, he quedado en empezar a trabajar directamente a trav\u00e9s del Consejo Federal de Inversiones (CFI) con las empresas de Israel para coordinar la tarea. Adem\u00e1s, pudimos conversar con gobernadores y gobernadoras de distintos partidos y tambi\u00e9n con empresarios, con la C\u00e1mara Israel\u00ed, y eso tambi\u00e9n es un aprendizaje\u201d, indic\u00f3.<\/p>\n<p>Por su parte, el gobernador de Mendoza, Rodolfo Su\u00e1rez, tambi\u00e9n ponder\u00f3 la experiencia al se\u00f1alar que fortalecer\u00e1 \u201cla cultura del agua\u201d que tiene su provincia. \u201cPertenezco a otro espacio pol\u00edtico, as\u00ed que debo agradecer la generosidad del Gobierno Nacional, de Wado, y de (el titular del CFI) Ignacio Lamothe, de haberme hecho parte de este viaje. El primer sentimiento que me llevo es de esperanza para nuestro pa\u00eds, pero de esperanza no dicho como una frase vac\u00eda sino como una esperanza de que lo que ocurre en Israel ocurra tambi\u00e9n en Argentina\u201d, se\u00f1al\u00f3 el gobernador mendocino.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-89441\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1755.jpg\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1755.jpg 640w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1755-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>La gobernadora de R\u00edo Negro, Arabela Carreras, en tanto, subray\u00f3 que \u201cha sido un viaje conmovedor desde lo pol\u00edtico\u201d, y remarc\u00f3 que \u201cesa conmoci\u00f3n ratifica lo que nos caracteriza a los argentinos, que es un gran optimismo y que, sin embargo, a veces, cuando estamos dentro del pa\u00eds, nos cuesta recordar\u201d. \u201cMe llevo una imagen de Israel, me llevo una nueva y maravillosa imagen de Argentina, que tambi\u00e9n es un gran pa\u00eds y tambi\u00e9n tiene grandes problemas. Entonces creo que tenemos una gran oportunidad de combinar nuestras fortalezas y nuestras debilidades\u201d, agreg\u00f3.<\/p>\n<p>El gobernador de San Juan, Sergio U\u00f1ac, por otra parte, agradeci\u00f3 al ministro de Pedro por la invitaci\u00f3n a la gira, y remarc\u00f3 que la misi\u00f3n fue \u201cespectacular\u201d. \u201cSan Juan puede tener una realidad muy parecida en cuanto a algunas de las actividades econ\u00f3micas. Las cosas que est\u00e1n bien hechas hay que hacerlas, repetirlas, copiarlas, proyectarlas, de acuerdo a la realidad y a las circunstancias que tenemos en nuestra propia idiosincrasia, pero hay que hacerlas r\u00e1pido, y \u00e9sta fue una experiencia fant\u00e1stica\u201d, apunt\u00f3.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-89442\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1777.jpg\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1777.jpg 640w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1777-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Alicia Kirchner, gobernadora de Santa Cruz, tambi\u00e9n destac\u00f3 la organizaci\u00f3n y la predisposici\u00f3n de los funcionarios nacionales durante la misi\u00f3n, y subray\u00f3 que se lleva \u201cuna gran experiencia sobre todo lo que tiene que ver con el avance de la tecnolog\u00eda, de la investigaci\u00f3n, y el gran aporte que es para el gobierno argentino\u201d.<\/p>\n<p>\u201cHemos fortalecido, as\u00ed lo siento, desde mi provincia, desde el interior, esa identidad y pertenencia que nos caracteriza a los argentinos. Tenemos que redoblar los esfuerzos, tenemos que generar trabajo con nuevas tecnolog\u00edas a trav\u00e9s de la ciencia y la investigaci\u00f3n, y a trav\u00e9s de la creatividad. Cuando N\u00e9stor nos dej\u00f3 nosotros dec\u00edamos que es imposible apagar tanto fuego, y alguien ac\u00e1 tambi\u00e9n dijo \u2018tengo un sue\u00f1o\u2019. Yo tambi\u00e9n tengo un sue\u00f1o, ese sue\u00f1o donde avancemos en investigaci\u00f3n, en nuevas tecnolog\u00edas\u201d, remarc\u00f3.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-89444\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1793.jpg\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1793.jpg 640w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1793-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>En tanto, el senador nacional por Santiago del Estero Jos\u00e9 Emilio Neder tambi\u00e9n agradeci\u00f3 la invitaci\u00f3n en representaci\u00f3n del gobernador Gerardo Zamora, y subray\u00f3: \u201cNos llevamos un ejemplo muy lindo. Hemos visto sorprendidos el crecimiento de este pa\u00eds, la tecnolog\u00eda aplicada a la producci\u00f3n es algo extraordinario, y cuando eso se hace en favor de mejorar la calidad de vida de la gente, es m\u00e1s importante a\u00fan\u201d.<\/p>\n<p>Adem\u00e1s, la ministra de Producci\u00f3n de La Pampa, Fernanda Gonz\u00e1lez, se\u00f1al\u00f3 que \u201csi bien la provincia tiene un territorio muy grande, presenta una gran superficie para desarrollar la agricultura bajo riego y para diversificar la matriz productiva\u201d. \u201cPara nosotros es muy importante ver esta realidad, c\u00f3mo se han modificado dentro de ese concepto, de esa problem\u00e1tica de escasez de agua, as\u00ed que espero que todo esto nos sirva y podemos desarrollar nuestra econom\u00eda en la provincia de La Pampa\u201d, indic\u00f3.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-89440\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1771-1024x683.jpg\" alt=\"\" width=\"640\" height=\"427\" \/><\/p>\n<p>Por \u00faltimo, el ministro de Agua y Energ\u00eda de La Rioja, Adolfo Scaglioni, tambi\u00e9n agradeci\u00f3 al ministro de Pedro por \u201cencargarse personalmente de que cada uno se sintiera importante\u201d, y ratific\u00f3 la importancia de la misi\u00f3n para el desarrollo del territorio. \u201cSomos la provincia con mayor carencia h\u00eddrica de toda Argentina, no nos podemos comparar con nadie, no tenemos un solo r\u00edo de superficie, imag\u00ednense lo que significa administrar este recurso en nuestra provincia. La agenda fue muy completa, nos lleva a sacar varias conclusiones: d\u00f3nde estamos parados y qu\u00e9 es lo que podemos hacer\u201d, subray\u00f3.<\/p>\n<p>El ministro del Interior, Wado de Pedro; junto a la embajadora de Israel en Argentina, Galit Ronen; ministros y funcionarios nacionales; y gobernadoras, gobernadoras y representantes de 10 provincias de Argentina; concluyeron hoy en Israel la misi\u00f3n de cooperaci\u00f3n cient\u00edfico tecnol\u00f3gica en el manejo del agua, que se desarroll\u00f3 del 22 al 28 de abril, y que incluy\u00f3 visitas a plantas de desalinizaci\u00f3n, riego y medici\u00f3n inteligente en distintos puntos de Israel, adem\u00e1s de una nutrida agenda de encuentros programados entre la comitiva argentina y funcionarios israel\u00edes, y con el propio presidente de Israel, Isaac Herzog.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-89439\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1733.jpg\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1733.jpg 640w, https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1733-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>La misi\u00f3n estuvo integrada, adem\u00e1s de Wado de Pedro, por los titulares de las carteras de Agricultura, Ganader\u00eda y Pesca, Juli\u00e1n Dom\u00ednguez; y de Ciencia y Tecnolog\u00eda, Daniel Filmus; as\u00ed como el vicejefe de Gabinete, Jorge Neme; y el secretario general del Consejo Federal de Inversiones (CFI), Ignacio Lamothe.<\/p>\n<p>Tambi\u00e9n participaron los gobernadores de Catamarca, Ra\u00fal Jalil; de Entre R\u00edos, Gustavo Bordet; de Formosa, Gildo Insfr\u00e1n; de Mendoza, Rodolfo Su\u00e1rez; de R\u00edo Negro, Arabela Carreras; de San Juan, Sergio U\u00f1ac; y de Santa Cruz, Alicia Kirchner, m\u00e1s senadores nacionales y equipos t\u00e9cnicos provinciales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u25a0 Lo hicieron gobernadores y gobernadoras. en el marco de la Cooperaci\u00f3n cient\u00edfico &#8211; tecnol\u00f3gica en el manejo del agua, en gira encabezada por el ministro del Interior, Wado de Pedro<\/p>\n","protected":false},"author":16,"featured_media":89438,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[13795,8159,4963],"class_list":["post-89437","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-gira","tag-israel","tag-wado-de-pedro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Destacan importancia de misi\u00f3n a Israel para el desarrollo econ\u00f3mico y tecnol\u00f3gico de las provincias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasmercedinas.com\/site\/2022\/04\/28\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Destacan importancia de misi\u00f3n a Israel para el desarrollo econ\u00f3mico y tecnol\u00f3gico de las provincias\" \/>\n<meta property=\"og:description\" content=\"\u25a0 Lo hicieron gobernadores y gobernadoras. en el marco de la Cooperaci\u00f3n cient\u00edfico - tecnol\u00f3gica en el manejo del agua, en gira encabezada por el ministro del Interior, Wado de Pedro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasmercedinas.com\/site\/2022\/04\/28\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\/\" \/>\n<meta property=\"og:site_name\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticiasmercedinas\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-28T20:53:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1574-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:site\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/04\\\/28\\\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/04\\\/28\\\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\\\/\"},\"author\":{\"name\":\"NOTICIASMERCEDINAS.COM\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/84b59c099c28ff2e8b77d4ceec5d8063\"},\"headline\":\"Destacan importancia de misi\u00f3n a Israel para el desarrollo econ\u00f3mico y tecnol\u00f3gico de las provincias\",\"datePublished\":\"2022-04-28T20:53:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/04\\\/28\\\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\\\/\"},\"wordCount\":1123,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/04\\\/28\\\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/INT_1574-1.jpg\",\"keywords\":[\"gira\",\"israel\",\"wado de pedro\"],\"articleSection\":[\"Politica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/04\\\/28\\\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/04\\\/28\\\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/04\\\/28\\\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\\\/\",\"name\":\"Destacan importancia de misi\u00f3n a Israel para el desarrollo econ\u00f3mico y tecnol\u00f3gico de las provincias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/04\\\/28\\\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/04\\\/28\\\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/INT_1574-1.jpg\",\"datePublished\":\"2022-04-28T20:53:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/04\\\/28\\\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/04\\\/28\\\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/04\\\/28\\\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/INT_1574-1.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/INT_1574-1.jpg\",\"width\":640,\"height\":427},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/04\\\/28\\\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Destacan importancia de misi\u00f3n a Israel para el desarrollo econ\u00f3mico y tecnol\u00f3gico de las provincias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"description\":\"Mercedes, Buenos Aires, Argentina\",\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"width\":512,\"height\":512,\"caption\":\"NOTICIASMERCEDINAS.COM\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticiasmercedinas\\\/\",\"https:\\\/\\\/x.com\\\/notmercedinas\",\"https:\\\/\\\/www.instagram.com\\\/noticiasmercedinas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/84b59c099c28ff2e8b77d4ceec5d8063\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g\",\"caption\":\"NOTICIASMERCEDINAS.COM\"},\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/author\\\/anonimo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Destacan importancia de misi\u00f3n a Israel para el desarrollo econ\u00f3mico y tecnol\u00f3gico de las provincias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasmercedinas.com\/site\/2022\/04\/28\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\/","og_locale":"es_ES","og_type":"article","og_title":"Destacan importancia de misi\u00f3n a Israel para el desarrollo econ\u00f3mico y tecnol\u00f3gico de las provincias","og_description":"\u25a0 Lo hicieron gobernadores y gobernadoras. en el marco de la Cooperaci\u00f3n cient\u00edfico - tecnol\u00f3gica en el manejo del agua, en gira encabezada por el ministro del Interior, Wado de Pedro","og_url":"https:\/\/noticiasmercedinas.com\/site\/2022\/04\/28\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\/","og_site_name":"NOTICIASMERCEDINAS.COM","article_publisher":"https:\/\/www.facebook.com\/noticiasmercedinas\/","article_published_time":"2022-04-28T20:53:52+00:00","og_image":[{"width":640,"height":427,"url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1574-1.jpg","type":"image\/jpeg"}],"author":"NOTICIASMERCEDINAS.COM","twitter_card":"summary_large_image","twitter_creator":"@notmercedinas","twitter_site":"@notmercedinas","twitter_misc":{"Escrito por":"NOTICIASMERCEDINAS.COM","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasmercedinas.com\/site\/2022\/04\/28\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\/#article","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2022\/04\/28\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\/"},"author":{"name":"NOTICIASMERCEDINAS.COM","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/84b59c099c28ff2e8b77d4ceec5d8063"},"headline":"Destacan importancia de misi\u00f3n a Israel para el desarrollo econ\u00f3mico y tecnol\u00f3gico de las provincias","datePublished":"2022-04-28T20:53:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2022\/04\/28\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\/"},"wordCount":1123,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2022\/04\/28\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1574-1.jpg","keywords":["gira","israel","wado de pedro"],"articleSection":["Politica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasmercedinas.com\/site\/2022\/04\/28\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasmercedinas.com\/site\/2022\/04\/28\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\/","url":"https:\/\/noticiasmercedinas.com\/site\/2022\/04\/28\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\/","name":"Destacan importancia de misi\u00f3n a Israel para el desarrollo econ\u00f3mico y tecnol\u00f3gico de las provincias","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2022\/04\/28\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\/#primaryimage"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2022\/04\/28\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1574-1.jpg","datePublished":"2022-04-28T20:53:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2022\/04\/28\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasmercedinas.com\/site\/2022\/04\/28\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/2022\/04\/28\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\/#primaryimage","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1574-1.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2022\/04\/INT_1574-1.jpg","width":640,"height":427},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasmercedinas.com\/site\/2022\/04\/28\/destacan-importancia-de-mision-a-israel-para-el-desarrollo-economico-y-tecnologico-de-las-provincias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noticiasmercedinas.com\/site\/"},{"@type":"ListItem","position":2,"name":"Destacan importancia de misi\u00f3n a Israel para el desarrollo econ\u00f3mico y tecnol\u00f3gico de las provincias"}]},{"@type":"WebSite","@id":"https:\/\/noticiasmercedinas.com\/site\/#website","url":"https:\/\/noticiasmercedinas.com\/site\/","name":"NOTICIASMERCEDINAS.COM","description":"Mercedes, Buenos Aires, Argentina","publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasmercedinas.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasmercedinas.com\/site\/#organization","name":"NOTICIASMERCEDINAS.COM","url":"https:\/\/noticiasmercedinas.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","width":512,"height":512,"caption":"NOTICIASMERCEDINAS.COM"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticiasmercedinas\/","https:\/\/x.com\/notmercedinas","https:\/\/www.instagram.com\/noticiasmercedinas\/"]},{"@type":"Person","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/84b59c099c28ff2e8b77d4ceec5d8063","name":"NOTICIASMERCEDINAS.COM","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g","caption":"NOTICIASMERCEDINAS.COM"},"url":"https:\/\/noticiasmercedinas.com\/site\/author\/anonimo\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/89437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/comments?post=89437"}],"version-history":[{"count":1,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/89437\/revisions"}],"predecessor-version":[{"id":89445,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/89437\/revisions\/89445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media\/89438"}],"wp:attachment":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media?parent=89437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/categories?post=89437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/tags?post=89437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}