{"id":96101,"date":"2022-07-30T00:13:55","date_gmt":"2022-07-30T03:13:55","guid":{"rendered":"https:\/\/noticiasmercedinas.com\/site\/?p=96101"},"modified":"2022-07-30T00:13:55","modified_gmt":"2022-07-30T03:13:55","slug":"por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios","status":"publish","type":"post","link":"https:\/\/noticiasmercedinas.com\/site\/2022\/07\/30\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\/","title":{"rendered":"Por obras, habr\u00e1 corte de luz este s\u00e1bado y afectar\u00e1 a unos 400 usuarios"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-31885\" src=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/EDEN-Foto-interrupci\u00f3n-programada-1-1024x683.jpg\" alt=\"\" width=\"640\" height=\"427\" \/><\/p>\n<p>Cerca de 400 usuarios del servicio el\u00e9ctrico se ver\u00e1n afectados con un corte en el suministro en la ma\u00f1ana de este s\u00e1bado, seg\u00fan inform\u00f3 la empresa EDEN.<\/p>\n<p>EDEN inform\u00f3 que realizar\u00e1 el cambio de postes de media tensi\u00f3n, con el objetivo de mejorar la calidad del servicio, y que para poder realizar estas mejoras y como medida de seguridad, ser\u00e1 necesario interrumpir el servicio de 400 usuarios mientras se trabaja en la red el\u00e9ctrica.<\/p>\n<p>Los trabajos se realizar\u00e1n el d\u00eda s\u00e1bado 30 de julio de 7.00 a 12:30 horas en calle 114 por Acceso Sur, calle 110 hasta calle 49, y desde 110 por 45 hasta 18 y 41.<\/p>\n<p>\u00abEn caso de presentarse condiciones clim\u00e1ticas adversas, las actividades ser\u00e1n reprogramadas. Seguimos trabajando para llevar el mejor servicio a nuestros usuarios\u00bb, indicaron\u00a0 desde EDEN y dieron a conocer sus canales de gesti\u00f3n y reclamos:<\/p>\n<ul>\n<li>0800-999-3336: reclamos t\u00e9cnicos las 24 hs todos los d\u00edas<\/li>\n<li>0810-999-3336: consultas comerciales de lunes a viernes de 8 a 18 hs.<\/li>\n<li>App EDEN M\u00f3vil<\/li>\n<li>Sucursal Virtual: https:\/\/sucursalvirtual.edensa.com.ar\/<\/li>\n<li>WhatsApp: 3364 52-6944 wa.me\/543364526944<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u25a0 EDEN inform\u00f3 que los trabajos se realizar\u00e1n el d\u00eda s\u00e1bado 30 de julio de 7.00 a 12:30 horas en calle 114 por Acceso Sur, calle 110 hasta calle 49, y desde 110 por 45 hasta 18 y 41.<\/p>\n","protected":false},"author":16,"featured_media":31885,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[1801,34,36],"class_list":["post-96101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad","tag-corte-de-luz","tag-eden","tag-obras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Por obras, habr\u00e1 corte de luz este s\u00e1bado y afectar\u00e1 a unos 400 usuarios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasmercedinas.com\/site\/2022\/07\/30\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por obras, habr\u00e1 corte de luz este s\u00e1bado y afectar\u00e1 a unos 400 usuarios\" \/>\n<meta property=\"og:description\" content=\"\u25a0 EDEN inform\u00f3 que los trabajos se realizar\u00e1n el d\u00eda s\u00e1bado 30 de julio de 7.00 a 12:30 horas en calle 114 por Acceso Sur, calle 110 hasta calle 49, y desde 110 por 45 hasta 18 y 41.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasmercedinas.com\/site\/2022\/07\/30\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\/\" \/>\n<meta property=\"og:site_name\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticiasmercedinas\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-30T03:13:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/EDEN-Foto-interrupci\u00f3n-programada-1-e1638469970347.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:site\" content=\"@notmercedinas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"NOTICIASMERCEDINAS.COM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/07\\\/30\\\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/07\\\/30\\\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\\\/\"},\"author\":{\"name\":\"NOTICIASMERCEDINAS.COM\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/84b59c099c28ff2e8b77d4ceec5d8063\"},\"headline\":\"Por obras, habr\u00e1 corte de luz este s\u00e1bado y afectar\u00e1 a unos 400 usuarios\",\"datePublished\":\"2022-07-30T03:13:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/07\\\/30\\\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\\\/\"},\"wordCount\":196,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/07\\\/30\\\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/EDEN-Foto-interrupci\u00f3n-programada-1-e1638469970347.jpg\",\"keywords\":[\"corte de luz\",\"eden\",\"obras\"],\"articleSection\":[\"Sociedad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/07\\\/30\\\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/07\\\/30\\\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/07\\\/30\\\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\\\/\",\"name\":\"Por obras, habr\u00e1 corte de luz este s\u00e1bado y afectar\u00e1 a unos 400 usuarios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/07\\\/30\\\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/07\\\/30\\\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/EDEN-Foto-interrupci\u00f3n-programada-1-e1638469970347.jpg\",\"datePublished\":\"2022-07-30T03:13:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/07\\\/30\\\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/07\\\/30\\\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/07\\\/30\\\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/EDEN-Foto-interrupci\u00f3n-programada-1-e1638469970347.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/EDEN-Foto-interrupci\u00f3n-programada-1-e1638469970347.jpg\",\"width\":640,\"height\":427},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/2022\\\/07\\\/30\\\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por obras, habr\u00e1 corte de luz este s\u00e1bado y afectar\u00e1 a unos 400 usuarios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"description\":\"Mercedes, Buenos Aires, Argentina\",\"publisher\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#organization\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"contentUrl\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/LOGO-512.jpg\",\"width\":512,\"height\":512,\"caption\":\"NOTICIASMERCEDINAS.COM\"},\"image\":{\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticiasmercedinas\\\/\",\"https:\\\/\\\/x.com\\\/notmercedinas\",\"https:\\\/\\\/www.instagram.com\\\/noticiasmercedinas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/#\\\/schema\\\/person\\\/84b59c099c28ff2e8b77d4ceec5d8063\",\"name\":\"NOTICIASMERCEDINAS.COM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g\",\"caption\":\"NOTICIASMERCEDINAS.COM\"},\"url\":\"https:\\\/\\\/noticiasmercedinas.com\\\/site\\\/author\\\/anonimo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por obras, habr\u00e1 corte de luz este s\u00e1bado y afectar\u00e1 a unos 400 usuarios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasmercedinas.com\/site\/2022\/07\/30\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\/","og_locale":"es_ES","og_type":"article","og_title":"Por obras, habr\u00e1 corte de luz este s\u00e1bado y afectar\u00e1 a unos 400 usuarios","og_description":"\u25a0 EDEN inform\u00f3 que los trabajos se realizar\u00e1n el d\u00eda s\u00e1bado 30 de julio de 7.00 a 12:30 horas en calle 114 por Acceso Sur, calle 110 hasta calle 49, y desde 110 por 45 hasta 18 y 41.","og_url":"https:\/\/noticiasmercedinas.com\/site\/2022\/07\/30\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\/","og_site_name":"NOTICIASMERCEDINAS.COM","article_publisher":"https:\/\/www.facebook.com\/noticiasmercedinas\/","article_published_time":"2022-07-30T03:13:55+00:00","og_image":[{"width":640,"height":427,"url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/EDEN-Foto-interrupci\u00f3n-programada-1-e1638469970347.jpg","type":"image\/jpeg"}],"author":"NOTICIASMERCEDINAS.COM","twitter_card":"summary_large_image","twitter_creator":"@notmercedinas","twitter_site":"@notmercedinas","twitter_misc":{"Escrito por":"NOTICIASMERCEDINAS.COM","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasmercedinas.com\/site\/2022\/07\/30\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\/#article","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2022\/07\/30\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\/"},"author":{"name":"NOTICIASMERCEDINAS.COM","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/84b59c099c28ff2e8b77d4ceec5d8063"},"headline":"Por obras, habr\u00e1 corte de luz este s\u00e1bado y afectar\u00e1 a unos 400 usuarios","datePublished":"2022-07-30T03:13:55+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2022\/07\/30\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\/"},"wordCount":196,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2022\/07\/30\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/EDEN-Foto-interrupci\u00f3n-programada-1-e1638469970347.jpg","keywords":["corte de luz","eden","obras"],"articleSection":["Sociedad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasmercedinas.com\/site\/2022\/07\/30\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasmercedinas.com\/site\/2022\/07\/30\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\/","url":"https:\/\/noticiasmercedinas.com\/site\/2022\/07\/30\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\/","name":"Por obras, habr\u00e1 corte de luz este s\u00e1bado y afectar\u00e1 a unos 400 usuarios","isPartOf":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2022\/07\/30\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\/#primaryimage"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2022\/07\/30\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\/#primaryimage"},"thumbnailUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/EDEN-Foto-interrupci\u00f3n-programada-1-e1638469970347.jpg","datePublished":"2022-07-30T03:13:55+00:00","breadcrumb":{"@id":"https:\/\/noticiasmercedinas.com\/site\/2022\/07\/30\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasmercedinas.com\/site\/2022\/07\/30\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/2022\/07\/30\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\/#primaryimage","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/EDEN-Foto-interrupci\u00f3n-programada-1-e1638469970347.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2019\/10\/EDEN-Foto-interrupci\u00f3n-programada-1-e1638469970347.jpg","width":640,"height":427},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasmercedinas.com\/site\/2022\/07\/30\/por-obras-habra-corte-de-luz-este-sabado-y-afectara-a-unos-400-usuarios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/noticiasmercedinas.com\/site\/"},{"@type":"ListItem","position":2,"name":"Por obras, habr\u00e1 corte de luz este s\u00e1bado y afectar\u00e1 a unos 400 usuarios"}]},{"@type":"WebSite","@id":"https:\/\/noticiasmercedinas.com\/site\/#website","url":"https:\/\/noticiasmercedinas.com\/site\/","name":"NOTICIASMERCEDINAS.COM","description":"Mercedes, Buenos Aires, Argentina","publisher":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasmercedinas.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasmercedinas.com\/site\/#organization","name":"NOTICIASMERCEDINAS.COM","url":"https:\/\/noticiasmercedinas.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","contentUrl":"https:\/\/noticiasmercedinas.com\/site\/wp-content\/uploads\/2020\/06\/LOGO-512.jpg","width":512,"height":512,"caption":"NOTICIASMERCEDINAS.COM"},"image":{"@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticiasmercedinas\/","https:\/\/x.com\/notmercedinas","https:\/\/www.instagram.com\/noticiasmercedinas\/"]},{"@type":"Person","@id":"https:\/\/noticiasmercedinas.com\/site\/#\/schema\/person\/84b59c099c28ff2e8b77d4ceec5d8063","name":"NOTICIASMERCEDINAS.COM","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4dfbf16b4d17945bfb6341b2d19043457132fcf478a5ee04f42e959fd8f5df0a?s=96&d=mm&r=g","caption":"NOTICIASMERCEDINAS.COM"},"url":"https:\/\/noticiasmercedinas.com\/site\/author\/anonimo\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/96101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/comments?post=96101"}],"version-history":[{"count":1,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/96101\/revisions"}],"predecessor-version":[{"id":96102,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/posts\/96101\/revisions\/96102"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media\/31885"}],"wp:attachment":[{"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/media?parent=96101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/categories?post=96101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasmercedinas.com\/site\/wp-json\/wp\/v2\/tags?post=96101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}